{"id":29658,"date":"2017-10-20T08:00:03","date_gmt":"2017-10-20T06:00:03","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=29658"},"modified":"2022-05-01T09:09:17","modified_gmt":"2022-05-01T07:09:17","slug":"neuer-anstrich-fuer-die-edv","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/de\/neuer-anstrich-fuer-die-edv\/","title":{"rendered":"Neuer Anstrich f\u00fcr die EDV"},"content":{"rendered":"<p><a href=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Neuer anstrich f\u00fcr die edv\" class=\"alignright wp-image-29660\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color.jpg\" alt=\"Color\" width=\"1\" height=\"1\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color.jpg 300w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color-150x150.jpg 150w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color-100x72.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color-24x24.jpg 24w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color-48x48.jpg 48w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Color-96x96.jpg 96w\" sizes=\"auto, (max-width: 1px) 100vw, 1px\" \/><\/a>Die Hamburger Mega-Gruppe, ein genossenschaftlich organisierter Zusammenschluss von \u00fcber 5600 Malereibetrieben, setzt k\u00fcnftig auf Hana von SAP. Vom Umstieg auf die In-Memory-basierte Datenbanktechnologie verspricht sich der Gro\u00dfh\u00e4ndler eine insgesamt schnellere Datenverarbeitung und h\u00f6here Bedienerfreundlichkeit im Tagesgesch\u00e4ft. Hilfe bei der Einf\u00fchrung kam unter anderem vom Ettlinger SAP-Partner und Branchenexperten Cormeta.<\/p>\n<p>Die Hamburger Mega-Gruppe ist mit 1700 Mitarbeitern an \u00fcber 100 bundesweiten Standorten ein unabh\u00e4ngiger Gro\u00dfhandelspartner f\u00fcr das Fachhandwerk. Neben Farben und Putzen geh\u00f6rt zum Sortiment eigentlich alles, was f\u00fcr die Bereiche Sanierung, Renovierung und Modernisierung ben\u00f6tigt wird: von Boden- und Wandbel\u00e4gen \u00fcber Maschinen und Werkzeuge, D\u00e4mmsysteme bis zu Trockenbaustoffen. Dar\u00fcber hinaus bietet die Genossenschaft seinen Kunden und Mitgliedern ein breites Spek\u00adtrum an Bank- und Versicherungsdienstleistungen.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-3444566162\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-4148648363\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-4292772528\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/steampunk-summit\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n<h3>SAP-Basis w\u00e4chst mit<\/h3>\n<p>Die IT w\u00e4chst mit dem Unternehmen \u2013 das trifft im Besonderen auf die 1901 gegr\u00fcndete Mega zu: Seit 1996 ist die Genossenschaft SAP-Anwender. Anlass war schon damals das kontinuierliche Wachstum hervorgerufen durch Zuk\u00e4ufe und Fusionen mit anderen Genossenschaften und Gro\u00dfh\u00e4ndlern.<\/p>\n<p>Auch in den Folgejahren erweiterte sich das Vertriebsnetz kontinuierlich, neue Niederlassungen kamen hinzu und betriebswirtschaftliche Abl\u00e4ufe verteilten sich auf eine zunehmende Anzahl an Mitarbeitern.<\/p>\n<p>Um Transparenz zu schaffen, wurden weitere Integrationen ben\u00f6tigt. Anfang der Nullerjahre \u00adintegrierte Mega am Stammsitz in Hamburg ein neues Personalabrechnungssystem sowie das CRM 4.0 von SAP.<\/p>\n<p>Seit 2011 nutzt die Gruppe CRM 7.0 f\u00fcr den Au\u00dfendienst, und f\u00fcr bessere Abl\u00e4ufe im Service und der Auftragsbearbeitung wurden in den Jahren darauf sowohl eine Lager\u00adverwaltungssoftware als auch ein BI und ein Ticketsystem von SAP eingef\u00fchrt.<\/p>\n<p>Von Anfang an stand als Partner die Cormeta zur Seite. Ziel war dabei immer, aus einer zentralen Serverstruktur heraus m\u00f6glichst einheitliche Bearbeitungsprozesse f\u00fcr s\u00e4mtliche Niederlassungen zu erm\u00f6glichen \u2013 folgerichtig wurde 2015 mit der Einrichtung des SAP-Enterprise-Portals auch eine gemeinsame Benutzeroberfl\u00e4che geschaffen.<\/p>\n<p>Ein weiteres Ziel war auch, Prozesse im Sinne der Kunden zu verbessern. Ein innovatives Beispiel hierf\u00fcr ist sicherlich die im Zentrallager in Hannover eingesetzte Fu\u00dfbodenschneidemaschine, die sich direkt \u00fcber das zen\u00adtrale SAP-System ansteuern l\u00e4sst. Kundenauftr\u00e4ge k\u00f6nnen damit individuell nach Losgr\u00f6\u00dfe 1 angefertigt werden.<\/p>\n<p>\u201eWir haben aktuell 74.000 Produkte und bearbeiten f\u00fcr 45.000 Kunden rund 1,7 Millionen Auftr\u00e4ge pro Jahr\u201c<\/p>\n<p>berichtet Jens Hungershausen, Abteilungsleiter IT bei Mega.<\/p>\n<p>\u201eUm die j\u00e4hrlich wachsende Auftragslage effektiv zu bew\u00e4ltigen, ben\u00f6tigen wir eine leistungsf\u00e4hige IT-Infrastruktur, die unseren Anwendern schnell die richtigen Informationen zur Verf\u00fcgung stellt und Prozesse durchg\u00e4ngig und automatisiert aus dem ERP heraus anst\u00f6\u00dft.\u201c<\/p>\n<h3>Hana f\u00fcr schnellere Prozesssteuerung<\/h3>\n<p>Dementsprechend aufmerksam verfolgten Jens Hungershausen und sein Team von Anfang an die von der SAP lancierte In-Memory-Datenbank-Technologie SAP Hana. Ein Vortrag zum Thema SAP Simple Finance, der auf die neuen M\u00f6glichkeiten im Finanzmanagement Bezug nahm, \u00fcberzeugte schlie\u00dflich auch die Bereichsleitung und den Vorstand der Mega.<\/p>\n<p>Als den Verantwortlichen dann Ende 2015 ein passendes Lizenz- und Zukaufsangebot vorgelegt wurde, entschied man sich, den Datenbankwechsel von Oracle nach SAP Hana zu vollziehen.<\/p>\n<p>\u201eJeder, der heute eine SAP-Landschaft betreibt, wird irgendwann den Schritt in Richtung Hana gehen m\u00fcssen\u201c<\/p>\n<p>so der IT-Leiter.<\/p>\n<p>\u201eUm Transparenz zu schaffen, ben\u00f6tigen wir eine schnelle Datenverarbeitung sowie schlanke und anwenderfreundliche Prozesse \u2013 mit dem Wechsel auf SAP Hana schaffen wir die Voraussetzungen, neue bzw. erweiterte Auswertungsm\u00f6glichkeiten zu kreieren, mit denen wir schneller an die gew\u00fcnschten Informationen herankommen.\u201c<\/p>\n<p>So sieht Jens Hungershausen vor allem im Bereich Reporting noch viel Potenzial f\u00fcr Optimierungen:<\/p>\n<p>\u201eAuswertung und Analyse kosteten uns fr\u00fcher viele Wochenstunden \u2013 in der Regel bastelten wir manuell irgendwelche Zahlen in Excel aneinander und es kam h\u00e4ufig zu \u00dcbertragungsfehlern.\u201c<\/p>\n<p>Als Fachh\u00e4ndler legt Mega hohen Wert auf die Qualifizierung seiner Mitarbeiter.<\/p>\n<p>\u201eWir ben\u00f6tigen produktaffine Mitarbeiter im Vertrieb \u2013 sie sollen keine SAP-Experten sein, sondern gute Verk\u00e4ufer, die wir schnell an unsere Business-Prozesse gew\u00f6hnen k\u00f6nnen\u201c<\/p>\n<p>betont Jens Hungershausen und pr\u00e4zisiert:<\/p>\n<p>\u201eMit SAP Hana k\u00f6nnen wir die Abl\u00e4ufe insoweit optimieren, dass unsere Anwender schnell und komfortabel die richtigen Informationen erhalten. Diese treffen dann qualifiziertere Entscheidungen und es ergibt sich \u00addaraus automatisch ein verbessertes Bedienverh\u00e4ltnis \u2013 d. h. wir k\u00f6nnen Mitarbeiter schneller einlernen, es kommt zu weniger Fehlern in den Abl\u00e4ufen und dementsprechend gering ist auch der Aufwand bei der Fehlerkorrektur.\u201c<\/p>\n<h3>Schritt f\u00fcr Schritt ans Ziel<\/h3>\n<p>Ende 2015 fiel bei Mega der Startschuss f\u00fcr den internen Datenbankenwechsel nach Hana. Im ersten Schritt ging es f\u00fcr Hungershausen und sein Team vor allem darum, die f\u00fcr den Bereich Hana entsprechende Infrastruktur kennenzulernen und die dabei aufkommenden Fragen zu kl\u00e4ren.<\/p>\n<p>Dazu wurde ein Workshop anberaumt, bei dem gleicherma\u00dfen Experten der SAP sowie des SAP-Partners Cormeta vor Ort waren. Das Systemhaus begleitet Mega schon seit \u00fcber 20 Jahren und \u00fcbernimmt unter anderem den Service und Support aller SAP-Installationen.<\/p>\n<p>Der SAP-Partner hat seine Branchenl\u00f6sungen bereits komplett auf SAP S\/4 Hana optimiert und betreibt derzeit mehrere S\/4-Hana-Anwendungen f\u00fcr Entwicklungs- und Testzwecke im Haus.<\/p>\n<h3>Erarbeitung eines Sicherungskonzepts<\/h3>\n<p>Die erste gr\u00f6\u00dfere Entscheidung, die Jens Hungershausen und sein Team w\u00e4hrend der Einf\u00fchrung treffen mussten, war, ob man k\u00fcnftig den TDI-Ansatz (Tailored Data\u00adcenter Integration) verfolgen oder ein clientfertiges System aus Server und Storage nutzen will.<\/p>\n<p>Man entschied sich f\u00fcr Ersteres und damit f\u00fcr die M\u00f6glichkeit, das System um beliebige Komponenten erweitern zu k\u00f6nnen. Wichtig war in dem Zusammenhang auch die Erarbeitung eines Sicherungskonzepts.<\/p>\n<p>\u201eDie Datensicherung war f\u00fcr uns selbstverst\u00e4ndlich ein gro\u00dfes Thema, aber auch hier konnten wir gemeinsam mit Partnern wie Cormeta eine Struktur festlegen, bei der wir auf der sicheren Seite sind\u201c<\/p>\n<p>erkl\u00e4rt Jens Hungershausen.<\/p>\n<p>Heute l\u00e4uft SAP Hana bei Mega sowohl im Rechenzentrum als auch im Notrechenzentrum, beide sind identisch ausgelegt und werden mit zweimal 2 Tera\u00adbyte-Servern betrieben. Auf diesen Servern laufen sowohl das ERP- als auch das BW-System und sind im Notfall sofort verf\u00fcgbar.<\/p>\n<h3>Schnellere Durchlaufzeit schon im Standard<\/h3>\n<p>F\u00fcr den Wechsel auf die Hana-Datenbank wurde eine Testphase von drei Wochen anberaumt. Hierf\u00fcr w\u00e4hlte Mega 30 Mitarbeiter aus \u2013 ein Querschnitt aus allen Bereichen. Es wurde ein Testkatalog erarbeitet und mit einem Aufwand von zirka 2,5 Tagen pro Mitarbeiter im Testsystem gearbeitet. Ende M\u00e4rz 2016 konnte gewechselt werden.<\/p>\n<p>Jens Hungershausen und sein Team \u00fcberpr\u00fcfen jetzt nach und nach alle Reports auf ihre Laufzeiten \u2013 das sind bei Mega immerhin fast 1000. Manche laufen automatisch schneller, allein durch das neue System.<\/p>\n<p>Mithilfe des Code Inspector von SAP werden nun Optimierungsm\u00f6glichkeiten ermittelt. So konnten einige Auswertungen von einem halben Tag Durchlaufzeit auf sieben Minuten verk\u00fcrzt werden. Bei anderen wiederum muss noch etwas Hand angelegt werden.<\/p>\n<p>\u201eWir haben einen halben Tag Schulung in Anspruch genommen und bauen gerade internes Know-how auf\u201c<\/p>\n<p>so der IT-Leiter.<\/p>\n<p>\u201eAm Ende sind es aber einfach nur die Grundz\u00fcge anst\u00e4ndiger und guter Programmierung. Wenn man die beherrscht, dann hat man auch mit Hana kein Problem.\u201c<\/p>\n<p>So sind bereits an vielen Stellen Hana-spezifische Erweiterungspunkte eingebaut worden, auch in der Standardprogrammierung.<\/p>\n<p>\u201eAllein der Standard bringt da schon eine ganze Menge. Zum Beispiel hatte das Kundenstammblatt bei uns immer eine sehr hohe Laufzeit \u2013 das geht heute extrem schnell, ohne dass wir da irgendetwas tun mussten.\u201c<\/p>\n<h3>Benefits schon jetzt sp\u00fcrbar<\/h3>\n<p>Schon jetzt profitieren die Anwender von schnelleren Ergebnissen etwa bei der Auftragsbearbeitung oder der Disposition, wenn sie z. B. Kunden \u00fcber das CRM suchen oder ihre Dispositionslisten auffrischen.<\/p>\n<p>\u201eDas sind teilweise Effekte, die wir jetzt erst mal nur durch die neue Technologie haben, und als N\u00e4chstes werden wir die Prozesse nach dem S\/4-Prinzip der Simplifizierung aufbauen und diese Denkweise vorantreiben.\u201c<\/p>\n<p>Hungershausen meint damit unter anderem die Einf\u00fchrung von SAP S\/4 Hana Finance, von dessen Funktionalit\u00e4ten er sich qualitativ bessere Auswertungen verspricht. Durch die neue Datenbanktechnologie laufen betriebswirtschaftliche Auswertungen aber schon jetzt bedeutend schneller.<\/p>\n<p>Und das ist vor allem bei Auswertungen mit hohem Datenvolumen sp\u00fcrbar, z. B. bei einer Auftragssperre, bei der die gesperrten Auftr\u00e4ge der letzten sechs Monate selektiert werden, oder beim Auftrags-Check, der die Auftr\u00e4ge der letzten drei Monate selektiert und \u00fcberpr\u00fcft, ob der Auftrags-Liefer-Faktura-Status zueinanderpasst.<\/p>\n<p>\u201eF\u00fcr uns war das ein gro\u00dfer Technologiesprung. Wir sind gespannt, welche M\u00f6glichkeiten sich in Zukunft noch daraus \u00adergeben!\u201c<a href=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Neuer anstrich f\u00fcr die edv\" class=\"aligncenter size-full wp-image-29659\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese.jpg\" alt=\"Wolfram Wiese, SAP, Hana, S\/4\" width=\"800\" height=\"605\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese-768x581.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese-100x76.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese-480x363.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese-640x484.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/Wolfram-Wiese-720x545.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit dem Technologiewechsel auf Hana legt die Malereinkaufsgenossenschaft Mega ein solides Fundament f\u00fcr langfristige Prozessoptimierungen.<\/p>\n","protected":false},"author":38,"featured_media":29664,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[4,17703],"tags":[1065,12242,65,381,369,21219,236],"coauthors":[19920],"class_list":["post-29658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag-1710","tag-cormeta","tag-datenverarbeitung","tag-hana","tag-in-memory","tag-it","tag-s-4","tag-sap"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",400,202,false],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-768x389.jpg",768,389,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-100x51.jpg",100,51,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-480x243.jpg",480,243,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-640x324.jpg",640,324,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-720x364.jpg",720,364,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-960x486.jpg",960,486,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",18,9,false],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",1000,506,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",600,304,false],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665.jpg",600,304,false],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/10\/shutterstock_206798665-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Mit dem Technologiewechsel auf Hana legt die Malereinkaufsgenossenschaft Mega ein solides Fundament f\u00fcr langfristige Prozessoptimierungen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/de\/category\/management\/\" rel=\"category tag\">Business Management<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/de\/category\/mag-1710\/\" rel=\"category tag\">MAG 17-10<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3magpmp.greatsolution.dev\/de\/author\/e-3-magazin\/"},"comments_num_v2":"0 comments","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/29658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=29658"}],"version-history":[{"count":0,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/29658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/29664"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=29658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=29658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=29658"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=29658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}