{"id":41924,"date":"2018-05-24T11:00:58","date_gmt":"2018-05-24T09:00:58","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=41924"},"modified":"2024-01-19T14:51:43","modified_gmt":"2024-01-19T13:51:43","slug":"lizenz-rettung-naht-oder","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/de\/lizenz-rettung-naht-oder\/","title":{"rendered":"Lizenz-Rettung naht \u2013 oder?"},"content":{"rendered":"<p>Die seit vielen Jahren kontrovers diskutierte \u201eindirekte Nutzung\u201c ist lediglich die Spitze des Eisbergs. Die Lizenzierung von geistigem Eigentum wie Algorithmen ist komplex und kompliziert.<\/p>\n<p>Die Analogie zu einem Eisberg in st\u00fcrmischer See ist soweit passend, dass sich die Wetterverh\u00e4ltnisse \u2013 die Vorgaben und W\u00fcnsche der Anbieter \u2013 sowie die Sichtweisen und Notwendigkeiten der Anwender fortlaufend \u00e4ndern \u2013 aufgrund der technischen Entwicklungen.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2403692980\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-2992709499\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-4115370497\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/steampunk-summit\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n<p>Und die wahren Probleme erkennt man erst bei genauer und detaillierter Beobachtung, denn \u201eindirekte Nutzung\u201c ist nur die Spitze \u2013 noch mehr Herausforderungen liegen unter der Wasseroberfl\u00e4che: Das Thema reicht von Berechtigungsmanagement \u00fcber Compliance bis hin zu Lizenzvermessungen!<\/p>\n<h3>Berechtigungsmanagement<\/h3>\n<p>SAP stellte im April dieses Jahres ein neues Vertriebs-, Audit- und Preismodell f\u00fcr die sogenannte indirekte Nutzung (Indirect Access) vor, das in enger Zusammenarbeit mit Anwendergruppen, Kunden, Partnern und Analysten entstanden ist.<\/p>\n<p>Der neue Ansatz soll daf\u00fcr sorgen, dass Kunden ihre SAP-Lizenzen k\u00fcnftiger leichter und transparenter nutzen k\u00f6nnen. Das Modell unterscheidet zwischen direktem\/menschlichem (Human Access) und indirektem\/digitalem Zugriff (Digital Access) und will klare Regeln bei den Themen Lizenzierung, Nutzung und Compliance schaffen. Es kommt somit Bewegung in die \u201eLizenz-Szene\u201c.<\/p>\n<p>Aufgrund neuer Anwendungsf\u00e4lle wie IoT, Blockchain und Industrie 4.0 werden neue Lizenz-Modelle notwendig, die \u00fcber die Beziehung Mensch\/Software hinausgehen.<\/p>\n<p>Die Herausforderungen sind gewaltig, weil eine Lizenz- und Berechtigungs-Architektur hinsichtlich Organisation, Betriebswirtschaft und Technik geschaffen werden muss:<\/p>\n<p>Accenture ist eine Kooperation mit SAP eingegangen, um eine intelligente L\u00f6sung f\u00fcr das Berechtigungsmanagement zu entwickeln. Die speziell f\u00fcr Hightech-Firmen konzipierte L\u00f6sung soll es den Anwendern erm\u00f6glichen, neue digitale Gesch\u00e4ftsmodelle schnell und einfach zu entwickeln, umzusetzen und zu skalieren.<\/p>\n<h3>Compliance<\/h3>\n<p>Weiters will SAP eine klare Trennung zwischen Lizenzvertrieb sowie Audit und Compliance einf\u00fchren und au\u00dferdem neue Regeln bei Organisation und Governance schaffen, die eine strikte Trennung zwischen Vertriebsorganisation und -prozessen und der Auditorganisation und deren Prozessen vorsehen.<\/p>\n<p>Bis heute kommt es immer wieder zu Differenzen zwischen Kunden und SAP, wie \u00e4ltere Vertragswerke hinsichtlich der neuen digitalen Anforderungen zu interpretieren sind.<\/p>\n<p>Dies wirkt sich teilweise negativ auf parallel verlaufende Gespr\u00e4che zur Neuanschaffung von Software aus. Die organisatorischen \u00c4nderungen auf SAP-Seite erlauben nun die Trennung dieser Sachverhalte und sollen unabh\u00e4ngige Diskussionen erm\u00f6glichen.<\/p>\n<p>Das k\u00f6nnte Kunden und Mitarbeitern aus dem SAP-Vertrieb die Zusammenarbeit erleichtern. Ebenso plant man, Messwerkzeuge zur Verf\u00fcgung zu stellen, sodass Bestandskunden in der Lage sind, ihren eigenen User- und Lizenz-Verbrauch jederzeit selbst zu \u00fcberwachen.<\/p>\n<p>Erg\u00e4nzend dazu Analyst Ray Wang von Constellation Re\u00adsearch:<\/p>\n<p><em>\u201eDurch die digitale Transformation muss jedes Unternehmen f\u00fcr sich kl\u00e4ren, wie es seinen Kunden neuen Mehrwert schafft. Sobald Unternehmen ihre Gesch\u00e4ftsmodelle von Produkten hin zu Dienstleistungen, von Dienstleistungen hin zum Kundenerlebnis, vom Erlebnis hin zu messbaren Ergebnissen entwickeln, wirkt sich das auch auf Preismodelle aus. <\/em><\/p>\n<p><em>Anbieter von Unternehmenssoftware bewegen sich daher nicht nur in Richtung outcome-orientierter Preise. Sie m\u00fcssen auch Modelle finden, die einerseits bisherige IT-Investitionen sch\u00fctzen, es Kunden aber andererseits auch erm\u00f6glichen, fair und gerecht auf neue Gesch\u00e4ftsmodelle zu wechseln.\u201c<\/em><\/p>\n<h3>Indirekte Nutzung<\/h3>\n<p>Ist \u201eindirekte Nutzung\u201c ein Mythos der SAP oder kann man die Ansicht vertreten, dass die Interaktion von Software-Komponenten deren urs\u00e4chliche Bestimmung ist?<\/p>\n<p><em>\u201eNun, von einem Mythos kann man nicht sprechen\u201c<\/em><\/p>\n<p>meint Technik- und Lizenzexperte Guido Schneider von Aspera.<\/p>\n<p><em>\u201eIch vermute, dass SAP damit urspr\u00fcnglich Missbrauch bek\u00e4mpfen wollte. Es ist technisch gesehen sehr leicht, eine Non-SAP-Applikation neben einem SAP-System aufzubauen. <\/em><\/p>\n<p><em>Die Mitarbeiter melden sich dann an der Non-SAP-Applikation an statt direkt am SAP-System. Die SAP-Transaktionen und -Reports lassen sich via BAPIs aufrufen und extern abbilden. So k\u00f6nnen Kunden Hunderte oder Tausende User-Lizenzen sparen. <\/em><\/p>\n<p><em>Das ist Lizenzmissbrauch und laut Urheberrecht sogar eine kriminelle Handlung.\u201c<\/em><\/p>\n<p>In den Anfangstagen von R\/3 war es \u00e4hnlich \u2013 zum Vorteil der SAP: Wer auf einem IBM- AIX-Server RS\/6000 sein R\/3 installierte, brauchte unter dem Unix-Betriebssystem AIX nur zwei User, einen Administrator und das R\/3-System. Unabh\u00e4ngig davon, wie viele Anwender eine Ebene h\u00f6her mit R\/3 arbeiteten, die AIX-Lizenzzahlungen umfassten nur zwei User.<\/p>\n<p><em>\u201eDie Key Account Manager der SAP wissen heute nicht, wo Missbrauch aufh\u00f6rt und wo bestimmungsgem\u00e4\u00dfe Nutzung anf\u00e4ngt. Mit Dollarzeichen in den Augen sind sie seit Ende 2014 und verst\u00e4rkt Mitte 2015 auf ihre Kunden zugegangen\u201c<\/em><\/p>\n<p>res\u00fcmiert Guido Schneider.<\/p>\n<p><em>\u201eDieses Verhalten hat zu einem Vertrauensbruch gegen\u00fcber SAP gef\u00fchrt. Das waren die Kunden nicht gewohnt. Fr\u00fcher war SAP ein Partner, der den Bestandskunden geholfen hat, ihre Gesch\u00e4ftsprozesse zu optimieren und in Software abzubilden.\u201c<\/em><\/p>\n<p>Anders als bisherige nutzungsbasierte Lizenzmodelle f\u00fcr den indirekten Zugriff auf ERP-Anwendungen orientiert sich das neue SAP-Lizenzmodell an der Wertsch\u00f6pfung, die durch das Anlegen bestimmter Dokumente im SAP-ERP-System erzielt wird.<\/p>\n<p><em>\u201eSAP hat mit diesem innovativen Modell einen wichtigen Schritt getan, das Vertrauen der Kunden zur\u00fcckzugewinnen, das in letzter Zeit etwas ver\u00adloren gegangen schien\u201c<\/em><\/p>\n<p>sagte Andreas Oczko, DSAG-Vorstand Operations\/Service &amp; Support und stellvertretender Vorstandsvorsitzender.<\/p>\n<p>Bez\u00fcglich des angek\u00fcndigten SAP-Preismodells f\u00fcr das Internet der Dinge ist f\u00fcr den Verein DSAG eine L\u00f6sung erstrebenswert, die sowohl aktuellen als auch zuk\u00fcnftigen Anforderungen gerecht wird.<\/p>\n<p><em>\u201eEin erster Schritt ist getan, um den Weg zur digitalen Transformation weiter zu gehen. Ziel muss es jedoch sein, ein echtes, atmendes Modell auf der Basis eines Pay-per-Use-Ansatzes zu entwickeln\u201c<\/em><\/p>\n<p>konkretisiert Andreas Oczko.<\/p>\n<p>Daf\u00fcr und f\u00fcr weitere Themen wird sich die DSAG in den kommenden Abstimmungsgespr\u00e4chen mit SAP f\u00fcr ihre Mitglieder weiter starkmachen. Die Forderung der SAP nach den \u201eSAP NetWeaver Foundation for Third Party Applica\u00adtions\u201c-Lizenzen l\u00e4sst sich jedoch als Mythos entlarven.<\/p>\n<p><em>\u201eHier handelt es sich um Inter\u00adoperabilit\u00e4t mit anderen Computerprogrammen\u201c<\/em><\/p>\n<p>erkl\u00e4rt Guido Schneider.<\/p>\n<p><em>\u201eDaf\u00fcr darf SAP keine zus\u00e4tzlichen Geb\u00fchren verlangen. Das hat aber nichts mit indirekter Nutzung zu tun. Das wird oft in einen Topf geworfen, weil der SAP-Vertrieb diese Themen auch nicht auseinanderhalten kann. <\/em><\/p>\n<p><em>Und wenn er mit dem einen Thema bei seinen Kunden \u2013 zu Recht \u2013 auf Granit gesto\u00dfen ist, versucht er die andere Karte auszuspielen.\u201c<\/em><\/p>\n<h3>Dritt-Add-ons<\/h3>\n<p>Bisher orientierte sich das Lizenzmodell f\u00fcr SAP ERP an der Zahl der Nutzer (User). Inzwischen finden aber immer mehr digitale Zugriffe auf SAP-Systeme statt. Eine Herausforderung f\u00fcr Kunden, die deshalb verst\u00e4rkt ein alternatives Lizenzmodell w\u00fcnschen.<\/p>\n<p>Zuk\u00fcnftig unterscheidet SAP zwischen Human Access, der nach User-Anzahl berechnet wird, und Digital Access, Zugriff \u00fcber Dritte, Internet of Things (IoT), Bots und\/oder andere digitale Zug\u00e4nge, die auf Basis der vom System selbst verarbeiteten Dokumente lizenziert werden k\u00f6nnen.<\/p>\n<p>Nach Meinung von SAP funktioniert es technisch wie folgt: Direkter Zugriff\/Human Access erfolgt, wenn ein Nutzer auf den digitalen Kern von SAP \u00fcber eine Schnittstelle zugreift, die mit oder als Teil der SAP-Software bereitgestellt wird.<\/p>\n<p>Indirekter Zugriff\/Digital Access erfolgt, wenn Ger\u00e4te, Bots oder automatisierte Systeme auf den digitalen Kern zugreifen. Oder wenn Personen, Ger\u00e4te oder Systeme den digitalen Kern indirekt \u00fcber eine zwischengeschaltete Software eines anderen Anbieters nutzen \u2013 zum Beispiel ein Nicht-SAP-Front-End, eine eigenentwickelte Kundenl\u00f6sung oder die Anwendung eines Drittanbieters. Logisch und fair?<\/p>\n<p><em>\u201eAuf gar keinen Fall\u201c<\/em><\/p>\n<p>meint Guido Schneider.<\/p>\n<p><em>\u201eEs widerspricht sogar dem Mitbewerberschutz (\u00a7 4 UWG). Dieses dient zum Schutz der Anbieter von Non-SAP-Applikationen und soll einen unverf\u00e4lschten Wettbewerb gew\u00e4hrleisten. <\/em><\/p>\n<p><em>Aber auch die Beziehungen zwischen SAP-Kunden und SAP sollen durch die Richtlinie 2005\/29\/EG gegen unlautere Gesch\u00e4ftspraktiken gesch\u00fctzt werden. Dar\u00fcber hinaus verst\u00f6\u00dft es wahrscheinlich ebenfalls gegen das Kartellrecht. Daran \u00e4ndert auch das neue Preismodell nichts. <\/em><\/p>\n<p><em>Dieses neue Preismodell der SAP f\u00fcr indirekte Nutzung hilft n\u00e4mlich nur einem, der SAP. Hiermit kann sie endlich indirekte Nutzung messen und zugleich in der neuen digitalen Welt die Kunden zur Kasse bitten. Hiermit wird SAP nur mehr Geld verdienen, sonst nichts.\u201c<\/em><\/p>\n<p>Nat\u00fcrlich muss sich das neue SAP-Preismodell erst noch in der Realit\u00e4t bew\u00e4hren. Wichtig in dem Zusammenhang w\u00e4re, dass SAP individuelle Gespr\u00e4che sucht, um zeitnah eine tragf\u00e4hige und faire L\u00f6sung f\u00fcr die indirekte Nutzung unter Ber\u00fccksichtigung der Altvertr\u00e4ge und der Historie zu finden.<\/p>\n<p><em>\u201eDiese Vereinbarungen m\u00fcssen legal verbindlich, f\u00fcr beide Seiten nachhaltig und wirtschaftlich sinnvoll sein und einen Schlussstrich unter dieses Thema ziehen\u201c<\/em><\/p>\n<p>erg\u00e4nzt Andreas Oczko.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/e3magpmp.greatsolution.dev\/partners\/aspera-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" title=\"Lizenz-rettung naht \u2013 oder?\" class=\"aligncenter wp-image-11356 size-full\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera.jpg\" alt=\"https:\/\/e3magpmp.greatsolution.dev\/partners\/aspera-gmbh\/\" width=\"1000\" height=\"112\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera.jpg 1000w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera-768x86.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera-100x11.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera-480x54.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera-640x72.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera-720x81.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-Aspera-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gibt es einen Ausweg aus dem Lizenz-Dilemma, mit dem Anbieter und Anwender leben k\u00f6nnen und wollen? Vereinfacht dargestellt: Seit dem Aufkommen des Client\/Server-Computing herrscht schwere See im Lizenzbetrieb und es gibt nur wenige Leuchtt\u00fcrme.<\/p>\n","protected":false},"author":2,"featured_media":41925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[161,2,22863],"tags":[8179,4186,824,370,13316,7799],"coauthors":[27825],"class_list":["post-41924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-szene","category-sap-nachrichten","category-mag-1806","tag-berechtigungsmanagement","tag-indirekte-nutzung","tag-internet-of-things","tag-iot","tag-lizenzierung","tag-sap-lizenzen"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",400,180,false],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-768x346.jpg",768,346,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-100x45.jpg",100,45,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-480x216.jpg",480,216,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-640x288.jpg",640,288,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-720x324.jpg",720,324,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",1000,450,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694.jpg",600,270,false],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/05\/shutterstock_520221694-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Gibt es einen Ausweg aus dem Lizenz-Dilemma, mit dem Anbieter und Anwender leben k\u00f6nnen und wollen? Vereinfacht dargestellt: Seit dem Aufkommen des Client\/Server-Computing herrscht schwere See im Lizenzbetrieb und es gibt nur wenige Leuchtt\u00fcrme.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/de\/category\/szene\/\" rel=\"category tag\">Szene<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/de\/category\/sap-nachrichten\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/de\/category\/mag-1806\/\" rel=\"category tag\">MAG 18-06<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3-Magazin","url":"https:\/\/e3magpmp.greatsolution.dev\/de\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comments","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/41924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/comments?post=41924"}],"version-history":[{"count":1,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/41924\/revisions"}],"predecessor-version":[{"id":138104,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/posts\/41924\/revisions\/138104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/media\/41925"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/media?parent=41924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/categories?post=41924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/tags?post=41924"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/de\/wp-json\/wp\/v2\/coauthors?post=41924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}