{"id":111986,"date":"2022-03-18T08:00:00","date_gmt":"2022-03-18T07:00:00","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=111986"},"modified":"2022-02-16T10:45:39","modified_gmt":"2022-02-16T09:45:39","slug":"paperless-rapport-in-r-3","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/paperless-rapport-in-r-3\/","title":{"rendered":"Informes sin papel en R\/3"},"content":{"rendered":"<p>Hasta 2019, los t\u00e9cnicos de Securiton recib\u00edan sus pedidos en forma de formulario o correo electr\u00f3nico y cumplimentaban sus informes de servicio en papel en las instalaciones del cliente. A continuaci\u00f3n, los informes deb\u00edan transferirse desde la oficina a los m\u00f3dulos PS y CS de SAP R\/3 para su posterior procesamiento y facturaci\u00f3n. Este proceso era largo y propenso a errores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"transparente-kommunikation\" data-block-type=\"core\">Comunicaci\u00f3n transparente<\/h3>\n\n\n\n<p>Securiton es el proveedor l\u00edder de tecnolog\u00eda y sistemas de seguridad en Suiza y est\u00e1 especializado en la instalaci\u00f3n y el mantenimiento de sistemas de alarma y sistemas de seguridad en las \u00e1reas de protecci\u00f3n contra incendios, protecci\u00f3n contra intrusi\u00f3n, control de accesos, videovigilancia, sistemas de gesti\u00f3n de la seguridad y protecci\u00f3n m\u00f3vil de la propiedad. 275 t\u00e9cnicos est\u00e1n a disposici\u00f3n de los clientes las 24 horas del d\u00eda para la instalaci\u00f3n y puesta en marcha en la construcci\u00f3n de sistemas y para la inspecci\u00f3n, mantenimiento y reparaci\u00f3n en el servicio de atenci\u00f3n al cliente.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-141161374\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-3206570277\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-1436902221\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n\n\n\n<p>Para estandarizar y digitalizar los procesos de servicio en las cuatro regiones ling\u00fc\u00edsticas de Suiza, mejorar la calidad de los datos, la transparencia y la capacidad de planificaci\u00f3n y optimizar la utilizaci\u00f3n de los t\u00e9cnicos de servicio, Securiton evalu\u00f3 primero varias soluciones de gesti\u00f3n de servicios de campo. Finalmente se decidi\u00f3 por mobileX porque las soluciones m\u00f3viles se pueden utilizar para port\u00e1tiles y tel\u00e9fonos m\u00f3viles y se pueden integrar en SAP PS y CS. Otro criterio importante fue el monitor de liberaci\u00f3n de mobileX, que se utiliza para comprobar la correcci\u00f3n de los comentarios digitales de los t\u00e9cnicos antes de publicarlos en SAP. <\/p>\n\n\n\n<p>La operaci\u00f3n piloto comenz\u00f3 en agosto de 2019 con la sucursal m\u00e1s grande de Berna. El despliegue en todas las regiones ling\u00fc\u00edsticas y en las ocho sucursales principales tuvo lugar a partir de febrero de 2020. La formaci\u00f3n de los t\u00e9cnicos y expedidores se realiz\u00f3 primero in situ. Tambi\u00e9n se utiliz\u00f3 un concepto de usuario avanzado, en el que empleados experimentados instruyeron a sus colegas de otras sucursales. Adem\u00e1s, hubo muchos cursos instant\u00e1neos m\u00e1s peque\u00f1os sobre cuestiones espec\u00edficas de los equipos de Microsoft.\u00a0<\/p>\n\n\n\n<p>Los programadores de Securiton planifican ahora el despliegue de los t\u00e9cnicos de servicio con la herramienta de planificaci\u00f3n de despliegues mobileX-Dispatch. Se trata de instalaciones y puestas en servicio en la construcci\u00f3n de plantas, as\u00ed como de inspecciones, mantenimiento y reparaciones en el servicio de atenci\u00f3n al cliente. Las \u00f3rdenes pool tambi\u00e9n se utilizan para pedidos con mantenimiento. En este caso, el despachador distribuye el pedido a un equipo determinado. Un t\u00e9cnico de servicio que tenga tiempo y est\u00e9 cerca puede hacerse cargo del pedido y concertar una cita con el cliente para llevarlo a cabo. As\u00ed se fomenta la responsabilidad personal y la motivaci\u00f3n de los t\u00e9cnicos y tambi\u00e9n se evitan los tiempos muertos.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"mobil-mit-ios-und-android\" data-block-type=\"core\">M\u00f3vil con iOS y Android<\/h3>\n\n\n\n<p>Desde 2020, los 275 t\u00e9cnicos de servicio utilizan la aplicaci\u00f3n CrossMIP en iOS y Android y MIP for Field Service en port\u00e1tiles Windows para la tramitaci\u00f3n m\u00f3vil de pedidos y la documentaci\u00f3n. Estos port\u00e1tiles se conectan al sistema de detecci\u00f3n de riesgos in situ en las instalaciones del cliente mediante una interfaz para configurarlo y mantenerlo.<\/p>\n\n\n\n<p>Los t\u00e9cnicos utilizan la aplicaci\u00f3n para la tramitaci\u00f3n de pedidos (cambios de estado, confirmaciones, informes de servicio) y la gesti\u00f3n de materiales (consumo de material, transferencias, devoluciones e inventario). Los t\u00e9cnicos pueden cambiar entre las tres versiones ling\u00fc\u00edsticas en alem\u00e1n, franc\u00e9s e italiano y, por ejemplo, mostrar el informe de servicio al cliente en su lengua materna.&nbsp;<\/p>\n\n\n\n<p>En MIP for Field Service, en su port\u00e1til, tambi\u00e9n pueden crear nuevos pedidos y generar sus informes diarios. Tambi\u00e9n pueden utilizarlo para solicitar sus vacaciones.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"r-3-im-backoffice\" data-block-type=\"core\">R\/3 en el back office<\/h3>\n\n\n\n<p>Todas las confirmaciones e informes de servicio se ejecutan en el monitor de liberaci\u00f3n, donde son comprobados por el personal de la oficina antes de ser contabilizados y facturados. De este modo se evitan reservas incorrectas y cancelaciones en SAP R\/3 que llevan mucho tiempo.<\/p>\n\n\n\n<p>Tras casi dos a\u00f1os de funcionamiento, Thomas Buser, director de proyectos inform\u00e1ticos de Securiton AG, saca una conclusi\u00f3n positiva del proyecto: <em>\"Los informes m\u00f3viles y sin papel han supuesto un aumento considerable de la eficiencia. Adem\u00e1s, nuestra gesti\u00f3n de almacenes se ha beneficiado mucho de la introducci\u00f3n de las soluciones de mobileX. Ahora tenemos transparencia sobre todas las piezas de los almacenes de veh\u00edculos. El inventario es mucho m\u00e1s f\u00e1cil y nos ahorra mucho tiempo y dinero. Adem\u00e1s, podemos utilizar las soluciones m\u00f3viles para almacenar informes de servicio con firmas de clientes a prueba de auditor\u00edas. El multiling\u00fcismo de las soluciones beneficia tanto a nuestros empleados como a nuestros clientes.\"<\/em> La migraci\u00f3n a la versi\u00f3n 10 de Field Service Management Suite de mobileX est\u00e1 prevista para los pr\u00f3ximos a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\" data-block-type=\"core\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/socios\/mobilex-ag\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx.jpg\" alt=\"https:\/\/e3magpmp.greatsolution.dev\/partners\/mobilex-ag\/\" class=\"wp-image-11371\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx.jpg 1000w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-768x86.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-100x11.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-480x54.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-640x72.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-720x81.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2017\/03\/CI-MOBILEx-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>En el pasado, los t\u00e9cnicos de Securiton, un proveedor suizo de tecnolog\u00eda de seguridad, rellenaban sus informes de servicio en papel en las instalaciones del cliente. A continuaci\u00f3n, el personal de la oficina ten\u00eda que transferir estos informes a SAP PS y CS.<\/p>","protected":false},"author":2460,"featured_media":111987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[4,40330],"tags":[867,989,140,450],"coauthors":[40004],"class_list":["post-111986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag-22-02","tag-mobilex","tag-papierlos","tag-ps","tag-r3"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",400,180,false],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-768x346.jpg",768,346,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-100x45.jpg",100,45,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-480x216.jpg",480,216,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-640x288.jpg",640,288,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-720x324.jpg",720,324,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",1000,450,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov.jpg",600,270,false],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2022\/02\/shutterstock-661898074-Sergii-Kovalov-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Fr\u00fcher f\u00fcllten die Techniker von Securiton, einem Schweizer Anbieter von Sicherheitstechnik, ihre Serviceberichte beim Kunden vor Ort auf Papier aus. Diese Berichte mussten dann vom Innendienst in SAP PS und CS \u00fcbertragen werden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/gestion\/\" rel=\"category tag\">Business Management<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-22-02\/\" rel=\"category tag\">MAG 22-02<\/a>","author_info_v2":{"name":"MobileX","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/mobilex\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/111986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2460"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=111986"}],"version-history":[{"count":0,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/111986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/111987"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=111986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=111986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=111986"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=111986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}