{"id":120562,"date":"2023-01-02T08:00:00","date_gmt":"2023-01-02T07:00:00","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=120562"},"modified":"2022-12-07T12:18:33","modified_gmt":"2022-12-07T11:18:33","slug":"tecnologia-fiscal-de-la-eficacia-a-la-precision","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/tecnologia-fiscal-de-la-eficacia-a-la-precision\/","title":{"rendered":"Tecnolog\u00eda fiscal - De la eficacia a la precisi\u00f3n"},"content":{"rendered":"<p>Por lo tanto, las funciones fiscales deben estar preparadas para hacer frente a esta ola de disrupci\u00f3n digital, que les exige estar a\u00fan m\u00e1s cerca de sus partes interesadas y satisfacer las cambiantes necesidades y expectativas de las administraciones tributarias.<\/p>\n\n\n\n<p>Tradicionalmente, las funciones fiscales han operado en silos y han sido pobres en tecnolog\u00eda, centr\u00e1ndose \u00e9sta principalmente en la eficiencia de los procesos. La tecnolog\u00eda fiscal representa el uso de la tecnolog\u00eda en la funci\u00f3n fiscal. La digitalizaci\u00f3n de los procesos, incluida la captura y el an\u00e1lisis de datos, la conciliaci\u00f3n de datos y la auditor\u00eda fiscal, permitir\u00e1 a las empresas optimizar los impuestos en todas sus operaciones y acelerar los procesos de planificaci\u00f3n, informaci\u00f3n y cumplimiento.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-3326762672\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-3964675187\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-1906582882\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n\n\n\n<p>Cumplir la normativa fiscal es m\u00e1s complejo y lleva m\u00e1s tiempo que nunca. Constantemente se aprueban nuevos impuestos y obligaciones de informaci\u00f3n. Un sistema de gesti\u00f3n del cumplimiento de la normativa fiscal se considera adecuado si es capaz tanto de reconocer los riesgos de infracciones significativas como de prevenirlas a tiempo y con suficiente certeza. Esto significa que se requieren medidas preventivas y de identificaci\u00f3n.<\/p>\n\n\n\n<p>Impulsados por las nuevas fronteras digitales y la globalizaci\u00f3n, los gobiernos recurren cada vez m\u00e1s a la tecnolog\u00eda para mejorar la recaudaci\u00f3n de impuestos indirectos. La herramienta m\u00e1s utilizada actualmente es probablemente la facturaci\u00f3n electr\u00f3nica.<\/p>\n\n\n\n<p>He aqu\u00ed una selecci\u00f3n de gobiernos que exigen la facturaci\u00f3n electr\u00f3nica de una forma u otra: Suecia est\u00e1 aplicando la directiva de la UE sobre facturaci\u00f3n electr\u00f3nica. Chile exige certificados digitales y n\u00fameros \u00fanicos para autenticar los documentos. M\u00e9xico exige sellos digitales para verificar el origen y la autenticidad de las facturas electr\u00f3nicas. Colombia exige a las empresas que utilicen la facturaci\u00f3n electr\u00f3nica para el IVA y el impuesto sobre bienes de consumo. El Gobierno rumano ha creado la plataforma central RO-E-Invoice. <\/p>\n\n\n\n<p>La facturaci\u00f3n electr\u00f3nica es obligatoria desde julio de 2022 para las empresas cuyas actividades comerciales est\u00e9n asociadas a categor\u00edas de productos con un alto riesgo fiscal. India anunci\u00f3 un cambio en el umbral de facturaci\u00f3n electr\u00f3nica. A partir del 1 de abril de 2023, la facturaci\u00f3n electr\u00f3nica ser\u00e1 obligatoria para los contribuyentes con ingresos superiores a 20 millones de INR (aproximadamente 2,4 millones de euros). Las autoridades alemanas est\u00e1n introduciendo el RTR o la facturaci\u00f3n electr\u00f3nica. La facturaci\u00f3n electr\u00f3nica B2B se introducir\u00e1 en Serbia a partir de enero de 2023. Australia exige a sus principales socios comerciales que presenten facturas electr\u00f3nicas en formato Peppol a partir de julio de 2023. Jap\u00f3n espera introducir la facturaci\u00f3n electr\u00f3nica en el pa\u00eds en octubre de 2023.<\/p>\n\n\n\n<p>En los \u00faltimos a\u00f1os, el IVA ha demostrado ser el mayor riesgo fiscal para muchas empresas. Esto se debe a que es susceptible de fraude, tiene una importancia considerable como ingreso fiscal y a menudo es objeto de auditor\u00edas por parte de las autoridades fiscales. Por ello, las autoridades fiscales comprueban peri\u00f3dicamente la exactitud de las facturas, el derecho a deducir el impuesto soportado y -sobre todo en el caso de las transacciones transfronterizas- las pruebas documentales y la contabilidad correcta en el \u00e1mbito del IVA.<\/p>\n\n\n\n<p>Los sistemas de control fiscal eficaces comprueban y controlan cada transacci\u00f3n contabilizada en el sistema ERP. Las comprobaciones de control pueden ir de simples a complejas, en funci\u00f3n de la jerarqu\u00eda organizativa. Por ejemplo, se podr\u00eda ilustrar la siguiente jerarqu\u00eda en complejidad:&nbsp;<\/p>\n\n\n\n<p>Primera etapa: Comprobaci\u00f3n de si las operaciones se han contabilizado sin indicador de impuestos. Segunda etapa: Comprobar la comparaci\u00f3n del tipo impositivo y el importe del impuesto en la factura. Tercera etapa: Comprobaci\u00f3n de las contabilizaciones incorrectas en las cuentas fiscales. Cuarta etapa: Comprobaci\u00f3n de la exactitud de los c\u00f3digos fiscales asignados para operaciones complejas como las operaciones en serie o las triangulaciones. Tomar esta cuarta etapa como ejemplo significa en realidad que las empresas establecen la compleja l\u00f3gica para la determinaci\u00f3n de impuestos una segunda vez en la instancia de auditor\u00eda e ilustra la complejidad de las auditor\u00edas hoy en d\u00eda.&nbsp;<\/p>\n\n\n\n<p>Al principio, la tecnolog\u00eda ten\u00eda como principal objetivo aumentar la eficiencia, por ejemplo en el procesamiento de facturas, mientras que cada vez m\u00e1s se est\u00e1 convirtiendo en una potente herramienta para comprobar la correcci\u00f3n.<\/p>\n\n\n\n<p>La introducci\u00f3n de la tecnolog\u00eda fiscal ofrece la oportunidad de analizar en profundidad y optimizar las funciones fiscales de una organizaci\u00f3n a nivel de transacci\u00f3n. En funci\u00f3n del alcance de los controles implantados, la tecnolog\u00eda fiscal no solo puede aumentar los requisitos de cumplimiento, sino tambi\u00e9n reducir costes, mejorar el control de procesos y datos, permitir una mejor planificaci\u00f3n y desarrollo de estrategias y aumentar la transparencia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Para hacer frente a los modelos de negocio digitales, las autoridades tributarias de todo el mundo reclaman una mayor transparencia mediante la divulgaci\u00f3n y el intercambio fluido de informaci\u00f3n sobre los contribuyentes entre las autoridades fiscales. <\/p>","protected":false},"author":2671,"featured_media":4163,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[10,42009],"tags":[40204,151,42010,5438],"coauthors":[42022],"class_list":["post-120562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-aktuelle-stichwort","category-mag-22-12","tag-das-aktuelle-stichwort","tag-e-invoicing","tag-mag-22-12","tag-pwc"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",400,172,false],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-768x331.jpg",768,331,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-100x43.jpg",100,43,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-480x207.jpg",480,207,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-640x276.jpg",640,276,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-720x310.jpg",720,310,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-960x414.jpg",960,414,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",1000,431,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort.jpg",600,259,false],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Das-aktuelle-Stichwort-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Um mit den digitalen Gesch\u00e4ftsmodellen umzugehen, fordern Steuerbeh\u00f6rden auf der ganzen Welt mehr Transparenz durch Offenlegung und den nahtlosen Austausch von Informationen \u00fcber den Steuerzahler zwischen den Steuerbeh\u00f6rden ein. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/opinion\/la-palabra-clave-actual\/\" rel=\"category tag\">Das aktuelle Stichwort<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-22-12\/\" rel=\"category tag\">Mag 22-12<\/a>","author_info_v2":{"name":"Rajasekhar Kancharla, PwC","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/rajasekhar-kancharla\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/120562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2671"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=120562"}],"version-history":[{"count":0,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/120562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/4163"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=120562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=120562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=120562"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=120562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}