{"id":131311,"date":"2023-08-09T08:00:00","date_gmt":"2023-08-09T06:00:00","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=131311"},"modified":"2023-08-22T16:01:02","modified_gmt":"2023-08-22T14:01:02","slug":"clean-master-data-for-s-4","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/clean-master-data-for-s-4\/","title":{"rendered":"Datos maestros limpios para S\/4"},"content":{"rendered":"<p>Adem\u00e1s, tambi\u00e9n puede tener sentido en el enfoque greenfield la conversi\u00f3n previa al Business Partner en ECC 6.0. En los proyectos de Adesso para la conversi\u00f3n a Business Partner y en las conversaciones mantenidas al respecto con nuestros clientes de SAP, surgen repetidamente dos cuestiones centrales que deben aclararse para evaluar el alcance del proyecto: \u00bfCu\u00e1l es la calidad de los datos de deudores, acreedores, personas de contacto y empleados? Y, \u00bfse mantienen los datos maestros de acuerdo con los requisitos de SAP S\/4 Hana?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Depuraci\u00f3n de datos<\/h2>\n\n\n\n<p><br>Estas preguntas no pueden responderse satisfactoriamente sin una evaluaci\u00f3n previa de los datos maestros. Sin embargo, las respuestas correctas a estas preguntas influyen en el esfuerzo de los departamentos para la depuraci\u00f3n de los datos maestros y en el curso ininterrumpido del plan general del proyecto para el -cambio de interlocutor comercial en ECC.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-1477002314\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-558714207\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2138393005\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n\n\n\n<p>Si est\u00e1 depurando los datos maestros, tambi\u00e9n se plantea la cuesti\u00f3n de si existen problemas de duplicados en los datos maestros. Puede convertir los duplicados en S\/4. Sin embargo, la chatarra de datos se trasladar\u00eda al nuevo sistema. Llevar la chatarra de datos al nuevo mundo S\/4 no tiene sentido. La promesa de SAP S\/4 Hana: la digitalizaci\u00f3n completa de los procesos empresariales s\u00f3lo puede lograrse con datos maestros limpios. Para nosotros, en Adesso, la soluci\u00f3n a este problema es obvia: los datos maestros deben elevarse a un nivel de calidad adecuado antes de la conversi\u00f3n. Con esto en mente, desarrollamos la herramienta de evaluaci\u00f3n de datos maestros, CVI Q-Check-Tool (CVI, Customer Vendor Integration), que se utiliza con \u00e9xito en nuestros proyectos y est\u00e1 totalmente integrada en nuestro modelo de proceso de Transformaci\u00f3n Activa para la conversi\u00f3n de socios comerciales. La herramienta CVI Q-Check soporta en tres niveles: Identificaci\u00f3n de campos de datos maestros no conformes con S\/4; comprobaci\u00f3n de duplicados (n\u00edtida y difusa, as\u00ed como con diferentes m\u00e9todos de b\u00fasqueda fon\u00e9tica si se desea); y evaluaci\u00f3n de la referencia de utilizaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\" data-block-type=\"core\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" data-block-type=\"core\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1.jpg\" alt=\"\" class=\"wp-image-131320\" style=\"width:743px;height:557px\" width=\"743\" height=\"557\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-400x300.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-768x576.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-100x75.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-480x360.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-640x480.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-720x540.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-16x12.jpg 16w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-1-1-600x450.jpg 600w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/><\/figure><\/div><\/div>\n<\/div>\n\n\n\n<p>La herramienta se transfiere al sistema ECC del cliente mediante una solicitud de transporte y proporciona listas de trabajo Excel f\u00e1ciles de usar que pueden procesarse en los departamentos y depurarse en ECC 6.0 (depuraci\u00f3n de datos). Otra ventaja es que no es necesario importar notas al sistema ECC, como ocurre con las herramientas est\u00e1ndar de SAP.<\/p>\n\n\n\n<p>En algunos proyectos, la herramienta Q-Check del IVC tambi\u00e9n descubri\u00f3 otros problemas, como rangos de n\u00fameros personalizados, etc., que en su d\u00eda se incorporaron al sistema ERP hace a\u00f1os pero que en realidad nunca se utilizaron o no se utilizar\u00e1n en el futuro.<\/p>\n\n\n\n<p>La herramienta CVI Q-Check se basa en un potente marco de trabajo (Q-Check). Adem\u00e1s de los m\u00e9todos de an\u00e1lisis contenidos en CVI Q-Check, pueden implementarse y utilizarse otros m\u00e9todos, por ejemplo, para comprobar si hay duplicados en el maestro de materiales o en otros objetos de datos maestros.<\/p>\n\n\n\n<p>Adem\u00e1s, los m\u00e9todos del marco Q-Check pueden integrarse en procesos operativos o flujos de trabajo, por ejemplo para comprobar sus reglas al crear datos maestros y proteger al usuario de la creaci\u00f3n de datos maestros poco limpios. De este modo, los datos maestros se mantienen limpios a largo plazo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3.jpg\" alt=\"\" class=\"wp-image-131326\" style=\"width:748px;height:561px\" width=\"748\" height=\"561\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-400x300.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-768x576.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-100x75.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-480x360.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-640x480.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-720x540.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-16x12.jpg 16w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/Web-2-3-600x450.jpg 600w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Conversi\u00f3n de socios comerciales<\/h2>\n\n\n\n<p><br>Nuestro modelo de proceso para la conversi\u00f3n de socios comerciales integra la evaluaci\u00f3n de los datos maestros directamente en la primera fase de nuestro modelo de proceso \"preparaci\u00f3n y an\u00e1lisis del proyecto\". Bas\u00e1ndose en los resultados, el proyecto de conversi\u00f3n de interlocutor comercial puede planificarse sin m\u00e1s riesgos y la carga de trabajo de los departamentos para la limpieza de datos puede determinarse en una fase temprana. Una vez que los departamentos han completado la limpieza de datos maestros, la conversi\u00f3n de interlocutores comerciales contin\u00faa con las dem\u00e1s fases del proyecto de acuerdo con el modelo de procedimiento de Adesso.&nbsp;<\/p>\n\n\n\n<p>El modelo de proceso, que incluye todas las actividades para el cambio de interlocutor comercial, ofrece la ventaja de que al principio se puede acordar junto con el cliente el nivel de las actividades a realizar, qui\u00e9n es responsable de qu\u00e9 actividades y qui\u00e9n las lleva a cabo. De este modo, el cliente puede participar en el cambio y obtener la m\u00e1xima transparencia sobre las actividades que se van a llevar a cabo.&nbsp;<\/p>\n\n\n\n<p>Si se pretende limpiar los datos maestros relevantes, el uso de la herramienta CVI Q-Check aumenta significativamente la eficiencia del proyecto y la transparencia para el cliente. Esto garantiza que la digitalizaci\u00f3n de los procesos empresariales pueda llevarse a cabo con \u00e9xito con datos maestros limpios.<\/p>\n\n\n\n<p>La combinaci\u00f3n del modelo de procesos de Adesso Active Transformation para la conversi\u00f3n de socios comerciales y la herramienta CVI Q-Check proporciona todo el contenido necesario para preparar de forma \u00f3ptima un sistema ECC para la conversi\u00f3n a S\/4 con datos maestros limpios y las actividades necesarias.<\/p>\n\n\n\n<p> <a href=\"https:\/\/www.adesso-orange.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">adesso-naranja.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Con la conversi\u00f3n de ECC 6.0 a S\/4, el concepto de interlocutor comercial, conocido desde hace tiempo, pasa a ser obligatorio. Por lo tanto, no es posible convertir un sistema ECC en el enfoque brownfield sin conversi\u00f3n previa.<\/p>","protected":false},"author":5435,"featured_media":131313,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[4,43277,1],"tags":[606,40601,3224,610],"coauthors":[43325],"class_list":["post-131311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-management","category-mag-23-07","category-uncategorized","tag-daten","tag-ecc-6-0-2","tag-enterprise-resource-planning","tag-stammdaten"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-768x346.jpg",768,346,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-100x45.jpg",100,45,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-480x216.jpg",480,216,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-640x288.jpg",640,288,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-720x324.jpg",720,324,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber.jpg",1000,450,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/08\/sauber-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Mit der Umstellung von ECC 6.0 auf S\/4 wird das seit Langem bekannte Business-Partner-Konzept verpflichtend. Es ist daher nicht m\u00f6glich, ein ECC-System im Brownfield-Ansatz ohne vorherige Umstellung zu konvertieren.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/gestion\/\" rel=\"category tag\">Business Management<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-23-07\/\" rel=\"category tag\">Mag 23-07<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/sin-categoria\/\" rel=\"category tag\">Uncategorized<\/a>","author_info_v2":{"name":"Leo Kurt Kaiser, Adesso Orange","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/leo-kaiser\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/131311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/5435"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=131311"}],"version-history":[{"count":6,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/131311\/revisions"}],"predecessor-version":[{"id":131668,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/131311\/revisions\/131668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/131313"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=131311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=131311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=131311"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=131311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}