{"id":140609,"date":"2024-03-21T07:00:00","date_gmt":"2024-03-21T06:00:00","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=140609"},"modified":"2024-03-18T08:43:40","modified_gmt":"2024-03-18T07:43:40","slug":"deber-de-diligencia-en-los-proyectos-de-elevacion-de-savia","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/deber-de-diligencia-en-los-proyectos-de-elevacion-de-savia\/","title":{"rendered":"Diligencia debida para proyectos SAP Rise"},"content":{"rendered":"<p>Esto se debe a que la soluci\u00f3n en memoria Hana ofrece un refuerzo de velocidad que hace posible la aplicaci\u00f3n de inteligencia artificial o an\u00e1lisis de big data en primer lugar gracias a procesos casi en tiempo real. Sin embargo, lo que a menudo sigue sin estar claro es c\u00f3mo llegar hasta ah\u00ed. Un despliegue on-prem en su propio centro de datos es tan posible para S\/4 Hana como un traslado a la nube. La mayor\u00eda de las empresas optar\u00e1n por una migraci\u00f3n a la nube por razones de coste y eficiencia, y tambi\u00e9n porque esto les da mucha m\u00e1s flexibilidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Ascenso con SAP o MSP<\/h2>\n\n\n\n<p><br>Existen dos opciones b\u00e1sicas para la variante en la nube: en primer lugar, la oferta Rise with SAP y, en segundo lugar, los servicios en la nube directos de proveedores externos. Los proveedores de servicios externos que act\u00faan como proveedores de servicios gestionados (MSP) ofrecen servicios de despliegue y funcionamiento para las instalaciones de S\/4 Cloud. Tambi\u00e9n proporcionan amplios servicios de acompa\u00f1amiento que van mucho m\u00e1s all\u00e1 del soporte de SAP para su propia oferta y, por lo tanto, son de crucial importancia. Por lo tanto, S\/4 Hana Cloud no significa necesariamente S\/4 en SAP Cloud.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2869532922\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-812383725\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-1720996761\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Con los anuncios en julio de 2023 y en el Congreso Anual de DSAG de desplegar innovaciones pioneras exclusivamente dentro de sus l\u00edneas de productos en la nube, SAP quiere sin duda aumentar las ventas de Rise with SAP. No obstante, es aconsejable no asumir compromisos precipitados a largo plazo en este asunto, ni siquiera por los cr\u00e9ditos y descuentos de SAP anunciados recientemente. En su lugar, las empresas deber\u00edan seguir la evoluci\u00f3n de las conversaciones en curso. Desde el punto de vista de la infraestructura, apenas hay razones para que las soluciones pioneras en la nube s\u00f3lo puedan funcionar exclusivamente en la infraestructura hyperscaler de SAP.<\/p>\n\n\n\n<p>Pero, \u00bfpor qu\u00e9 tanto escepticismo? El principio de ventanilla \u00fanica impresiona a primera vista. Sin embargo, el alcance del servicio es muy estandarizado y, por tanto, limitado. Rise no satisface adecuadamente las necesidades individuales. Aunque SAP promete un funcionamiento b\u00e1sico estable y se encarga de las actualizaciones cr\u00edticas del sistema, deja en manos de las empresas la comprobaci\u00f3n y aplicaci\u00f3n de las actualizaciones menos urgentes u opcionales.&nbsp;<\/p>\n\n\n\n<p>Cuando se trata de seguridad, la responsabilidad personal del cliente tambi\u00e9n pasa a primer plano. Ellos son los responsables de comprobar la pertinencia de las instrucciones de seguridad, planificar los pasos necesarios y ponerlos en pr\u00e1ctica a tiempo. A diferencia de lo que ocurre cuando se trabaja con un MSP, donde las comprobaciones peri\u00f3dicas de calidad y las reuniones de feedback asociadas son habituales, Rise no ofrece este tipo de comprobaciones. Esto obliga a las empresas a hacer frente a los posibles riesgos del sistema por iniciativa propia. En la mayor\u00eda de los casos, hay que adquirir los conocimientos y el personal necesarios. Adem\u00e1s, se incurre en costes adicionales por los servicios de acompa\u00f1amiento, independientemente de si se prestan internamente o a trav\u00e9s de terceros proveedores.<\/p>\n\n\n\n<p>Adem\u00e1s, Rise convierte el sistema en una especie de caja negra en la que es dif\u00edcil localizar cualquier error o problema. No obstante, las responsabilidades est\u00e1n claramente definidas en el contrato. El an\u00e1lisis de los problemas de rendimiento es responsabilidad del cliente, a menos que se adquiera otro de los ya numerosos paquetes adicionales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Supervisi\u00f3n de ERP<\/h2>\n\n\n\n<p><br>Las empresas pueden superar estas dificultades con una estrategia de supervisi\u00f3n bien pensada y centrada en una herramienta de supervisi\u00f3n. Es fundamental que est\u00e9 certificada por SAP. Tambi\u00e9n debe ser compatible con todas las formas de S\/4, ya sea en las instalaciones o en la nube, incluida la soluci\u00f3n Rise-with-SAP.<\/p>\n\n\n\n<p>Estas herramientas de supervisi\u00f3n, como PowerConnect para SAP, ofrecen informaci\u00f3n en tiempo real y ayudan a detectar fallos de forma temprana y preventiva. Al mismo tiempo, minimizan el tiempo necesario para la resoluci\u00f3n de problemas.<\/p>\n\n\n\n<p>Rise tiene sin duda ventajas, pero de ning\u00fan modo para todos los clientes SAP existentes. En cambio, los MSP pueden crear ofertas personalizadas. Por tanto, tiene sentido recabar opiniones adicionales, ya que las ventajas de una estrategia en la nube tambi\u00e9n pueden aprovecharse sin estar atado a un proveedor concreto.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.softwareone.com\/de-at\" target=\"_blank\" rel=\"noreferrer noopener\">softwareone.com<\/a><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>No es oro todo lo que reluce, ni siquiera en SAP. La supuesta<br \/>\nTodo paquete sin preocupaciones El ascenso con SAP tambi\u00e9n alberga escollos. Sin embargo, muchas empresas son conscientes de ello:<br \/>\nS\/4 Hana allana el camino para casos empresariales completamente nuevos e innovadores.<\/p>","protected":false},"author":2549,"featured_media":140611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[5,43842],"tags":[73],"coauthors":[40584],"class_list":["post-140609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infrastruktur","category-mag-24-03","tag-erp"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-768x346.jpg",768,346,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-100x45.jpg",100,45,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-480x216.jpg",480,216,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-640x288.jpg",640,288,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-720x324.jpg",720,324,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555.jpg",1000,450,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/03\/2403-50-Sorgfalt-shutterstock_296870555-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Es ist nicht alles Gold, was gl\u00e4nzt \u2013 auch nicht bei SAP. Das vermeintliche<br \/>\nRundum-sorglos-Paket Rise with SAP birgt auch T\u00fccken. Vielen Unternehmen ist jedoch klar:<br \/>\nS\/4 Hana ebnet den Weg zu v\u00f6llig neuen, innovativen Business-Cases.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/infraestructura\/\" rel=\"category tag\">IT Management<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-24-03\/\" rel=\"category tag\">MAG 24-03<\/a>","author_info_v2":{"name":"S\u00f6ren Genzler, SoftwareOne","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/soeren-genzler\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/140609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2549"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=140609"}],"version-history":[{"count":1,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/140609\/revisions"}],"predecessor-version":[{"id":140610,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/140609\/revisions\/140610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/140611"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=140609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=140609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=140609"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=140609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}