{"id":146250,"date":"2024-10-11T07:00:00","date_gmt":"2024-10-11T05:00:00","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=146250"},"modified":"2024-10-04T10:00:57","modified_gmt":"2024-10-04T08:00:57","slug":"logistica-dbh-ag-lo-que-somos","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/logistica-dbh-ag-lo-que-somos\/","title":{"rendered":"dbh Logistics IT AG: \u00bfQui\u00e9nes somos?"},"content":{"rendered":"<p>Como socio certificado de SAP, dbh ofrece una amplia cartera de soluciones SAP para aduanas y comercio exterior. Independientemente de la suite ERP utilizada (SAP ECC, SAP S\/4 HANA on-premise, nube privada o nube p\u00fablica), nuestras soluciones pueden utilizarse plenamente en cualquier lugar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Nuestras soluciones anteriores en el \u00e1mbito del comercio exterior\/aduanas<\/h2>\n\n\n\n<p>La implementaci\u00f3n de soluciones SAP plug-in cl\u00e1sicas basadas en ABAP no es posible sin un acceso remoto al sistema del cliente. A pesar del acceso a SAP, nuestros clientes no se ahorraron el trabajo de SAP Basis. Las configuraciones en SM59, la creaci\u00f3n de directorios AL11 y la importaci\u00f3n de solicitudes de transporte externas son s\u00f3lo algunos ejemplos de estas actividades. Las adaptaciones personalizadas, que se defin\u00edan en un taller, siempre requer\u00edan la implementaci\u00f3n en el propio sistema del cliente.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2430607182\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-54647164\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-3785018839\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Ejemplo pr\u00e1ctico: Origen de los bienes y preferencias<\/h2>\n\n\n\n<p>El origen de las mercanc\u00edas determina el pa\u00eds de fabricaci\u00f3n de un producto para las normas comerciales y los derechos de aduana, mientras que las preferencias son concesiones aduaneras otorgadas por acuerdos comerciales a determinados pa\u00edses de origen. La conversi\u00f3n de la soluci\u00f3n para el origen de las mercanc\u00edas y las preferencias (WuP) de un plugin basado en ABAP con una fuerte personalizaci\u00f3n a un enfoque modular nativo en la nube en la SAP Business Technology Platform (BTP) fue un paso clave en nuestra estrategia en la nube.<\/p>\n\n\n\n<p>En el entorno ABAP anterior, la soluci\u00f3n WuP estaba muy personalizada seg\u00fan los requisitos espec\u00edficos de los clientes. Estas personalizaciones individuales dieron lugar a un complejo entorno de sistemas dif\u00edcil de mantener y ampliar, ya que las versiones de los clientes permanec\u00edan en los respectivos sistemas locales. Cada proyecto de cliente requer\u00eda una amplia personalizaci\u00f3n y conocimientos espec\u00edficos, lo que alargaba los plazos de implantaci\u00f3n y limitaba la flexibilidad.<\/p>\n\n\n\n<p>El nuevo enfoque de ampliaci\u00f3n por separado permite que la soluci\u00f3n WuP sea modular y flexible. S\u00f3lo se activan los componentes realmente necesarios, mientras que las personalizaciones espec\u00edficas del cliente se integran como m\u00f3dulos independientes en el SAP BTP. De este modo, el n\u00facleo de la aplicaci\u00f3n se mantiene estable y f\u00e1cil de mantener (\"Keep the Core Clean\"), mientras que los requisitos individuales pueden implementarse de forma eficiente.<\/p>\n\n\n\n<p>Este enfoque minimiza la dependencia de una personalizaci\u00f3n en profundidad al no desarrollar dos veces requisitos similares, sino gestionarlos de forma modular. Los clientes se benefician de una soluci\u00f3n estandarizada f\u00e1cil de ampliar y que se complementa autom\u00e1ticamente con actualizaciones continuas sin comprometer la estabilidad de los sistemas existentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Desaf\u00edos<\/h2>\n\n\n\n<p>La conversi\u00f3n de plugins SAP (ABAP) a una arquitectura nativa en la nube, como es necesario para la soluci\u00f3n dbh de origen de mercanc\u00edas y preferencias (WuP), por ejemplo, conlleva una serie de retos:<\/p>\n\n\n\n<ul class=\"wp-block-list\" data-block-type=\"core\">\n<li data-block-type=\"core\"><strong>Gesti\u00f3n de datos<\/strong>El tratamiento y la gesti\u00f3n de grandes cantidades de datos, cruciales para el c\u00e1lculo de preferencias y pruebas de origen, deben garantizarse de forma segura y eficiente.<\/li>\n\n\n\n<li data-block-type=\"core\"><strong>Funcionalidad<\/strong>Garantizar que todas las funciones esenciales se mantienen en el nuevo entorno es una tarea compleja, ya que se introducen nuevas tecnolog\u00edas y arquitecturas y hay que combinar las funciones de personalizaci\u00f3n existentes para todos los clientes en una aplicaci\u00f3n mantenible y escalable.<\/li>\n\n\n\n<li data-block-type=\"core\"><strong>Interfaces de usuario<\/strong>Los clientes esperan interfaces personalizables y f\u00e1ciles de usar que respondan a los requisitos espec\u00edficos de su empresa. Esto requiere un dise\u00f1o flexible de los componentes del front-end.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Implantaci\u00f3n t\u00e9cnica \/ ventajas de las soluciones complementarias SAP de dbh<\/h2>\n\n\n\n<p>La SAP Build Work Zone es el punto de entrada central para nuestros clientes en las soluciones dbh SAP Cloud. Tiene una estructura modular, lo que significa que los clientes solo pueden activar las funciones espec\u00edficas que necesitan, como el almac\u00e9n de datos, las personalizaciones de UI5 o servicios adicionales espec\u00edficos. Esto reduce la complejidad y los costes. Pueden a\u00f1adirse nuevos m\u00f3dulos o servicios en cualquier momento sin que ello afecte a las implantaciones existentes. Como la soluci\u00f3n se basa en SAP BTP, puede crecer f\u00e1cilmente con la empresa. Se pueden integrar nuevos usuarios, m\u00e1s datos o aplicaciones adicionales con poco esfuerzo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Lecciones aprendidas<\/h2>\n\n\n\n<p>El cambio a una arquitectura nativa en la nube nos ha proporcionado valiosos conocimientos sobre los retos y oportunidades asociados a la introducci\u00f3n de nuevas tecnolog\u00edas en el entorno SAP. Pudimos adquirir importantes conocimientos sobre el nuevo entorno, especialmente en el contexto de innovaciones t\u00e9cnicas como el modelo de programaci\u00f3n de aplicaciones en la nube (CAP), UI5 en combinaci\u00f3n con Node.js y los distintos servicios BTP (como Destination, Connectivity y Event Mesh).<\/p>\n\n\n\n<p>Un punto clave que hemos identificado en nuestros proyectos es el considerable esfuerzo de aprendizaje que suponen las nuevas tecnolog\u00edas. Aunque el modelo CAP ofrece una base moderna y flexible para el desarrollo de aplicaciones, es fundamentalmente diferente de los enfoques tradicionales basados en ABAP. La necesidad de familiarizarse con nuevos lenguajes de programaci\u00f3n como Node.js y los frameworks cloud-native espec\u00edficos de SAP supone un reto, especialmente para los desarrolladores que anteriormente solo hab\u00edan trabajado en el mundo ABAP.<\/p>\n\n\n\n<p>Los servicios BTP, como Destino, Conectividad y Malla de Eventos, ofrecen potentes capacidades de integraci\u00f3n y el enfoque de la Arquitectura Dirigida a Eventos, pero tambi\u00e9n requieren una exploraci\u00f3n y comprensi\u00f3n en profundidad de los conceptos subyacentes. En la actualidad hay pocos enfoques normalizados o mejores pr\u00e1cticas en el mercado, lo que significa que cada proyecto representa una cierta cantidad de trabajo pionero.<\/p>\n\n\n\n<p>Optar por un enfoque greenfield forzado en la nube p\u00fablica de SAP y utilizar nuevos lenguajes de programaci\u00f3n conlleva retos cuando se carece de una amplia experiencia en el mercado y de mejores pr\u00e1cticas probadas. Estos retos pueden dar lugar a costes m\u00e1s elevados, plazos de implantaci\u00f3n m\u00e1s largos y mayores riesgos.<\/p>\n\n\n\n<p>Los clientes de SAP que opten por este enfoque deben estar dispuestos a invertir en investigaci\u00f3n y desarrollo para aprovechar las ventajas de las nuevas tecnolog\u00edas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Outlook<\/h2>\n\n\n\n<p>Como parte de nuestra estrategia \"Cloud First\", tenemos previsto ampliar continuamente nuestra cartera de productos. La atenci\u00f3n se centra en el desarrollo de soluciones nativas de la nube completamente nuevas que se basan \u00fanicamente en conceptos ABAP probados. Se trata de desarrollos \"greenfield\" que se dise\u00f1an desde cero y que pueden integrarse sin problemas en el moderno entorno en la nube de SAP, en constante evoluci\u00f3n. La atenci\u00f3n se centra en enfoques innovadores y preparados para el futuro.<\/p>\n\n\n\n<p>Nuestro objetivo es ofrecer siempre a nuestros clientes las herramientas m\u00e1s modernas y eficaces. Seguiremos ofreciendo soluciones flexibles, escalables y preparadas para el futuro gracias a nuestra estrecha conexi\u00f3n con los desarrollos de SAP, especialmente bajo el lema \"Rise With SAP\".<\/p>\n\n\n\n<p>La innovaci\u00f3n continua sigue siendo una parte central de nuestra estrategia para garantizar que nuestros productos satisfacen las crecientes demandas del mercado, al tiempo que utilizan los \u00faltimos avances tecnol\u00f3gicos en el entorno SAP. Esto nos permite no s\u00f3lo optimizar los procesos existentes, sino tambi\u00e9n abrir nuevas oportunidades de negocio para nuestros clientes.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.dbh.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">dbh.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>dbh Logistics IT AG es uno de los principales proveedores de soluciones de software y servicios de consultor\u00eda en las \u00e1reas de aduanas y comercio exterior, cumplimiento normativo, gesti\u00f3n del transporte, gesti\u00f3n portuaria, SAP y servicios en la nube.<\/p>","protected":false},"author":5596,"featured_media":146251,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[26405,44026,44020],"tags":[],"coauthors":[44029],"class_list":["post-146250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-advertorial","category-extra-2410","category-mag-24-10"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-400x180.jpg",400,180,true],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-768x346.jpg",768,346,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-100x45.jpg",100,45,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-480x216.jpg",480,216,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-640x288.jpg",640,288,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-720x324.jpg",720,324,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-18x8.jpg",18,8,true],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2.jpg",1000,450,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-600x270.jpg",600,270,true],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-600x450.jpg",600,450,true],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/10\/dbh_SAP_Solutions_2-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Die dbh Logistics IT AG z\u00e4hlt zu den f\u00fchrenden Anbietern von Softwarel\u00f6sungen und Beratungsdiensten in den Bereichen Zoll und Au\u00dfenhandel, Compliance, Transportmanagement, Hafenwirtschaft, SAP und Cloud-Services.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/publirreportaje\/\" rel=\"category tag\">Advertorial<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/extra-2410\/\" rel=\"category tag\">Extra 2410<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-24-10\/\" rel=\"category tag\">MAG 24-10<\/a>","author_info_v2":{"name":"dbh Logistics IT AG","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/dbh-logistics-it-ag\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/146250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/5596"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=146250"}],"version-history":[{"count":3,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/146250\/revisions"}],"predecessor-version":[{"id":146258,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/146250\/revisions\/146258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/146251"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=146250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=146250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=146250"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=146250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}