{"id":34436,"date":"2018-03-01T10:00:01","date_gmt":"2018-03-01T09:00:01","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=34436"},"modified":"2020-02-09T22:38:55","modified_gmt":"2020-02-09T21:38:55","slug":"instale-los-parches-requeridos-y-arranque-su-host","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/instale-los-parches-requeridos-y-arranque-su-host\/","title":{"rendered":"Instale los parches necesarios y reinicie su host"},"content":{"rendered":"<p>En un informe sobre los mega-GAU de seguridad Meltdown y Spectre con el impacto potencial en SAP Hana, tambi\u00e9n publicamos partes de la Nota SAP 2586312 (\u00bfC\u00f3mo protegerse contra las vulnerabilidades de ejecuci\u00f3n especulativa?) en el idioma original ingl\u00e9s, consulte la edici\u00f3n E-3 de febrero de 2018, p\u00e1gina 38.<\/p>\n<p>\"<em>Instale los parches necesarios y reinicie su host<\/em>\"\u00a1No se puede ser m\u00e1s irrespetuoso con los clientes actuales de SAP!<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-3073659314\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-1169998001\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-1050319338\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n<p>Incluso el personal no inform\u00e1tico sabe que un servidor Hana afectado por Meltdown y Spectre no puede reiniciarse sin una amplia preparaci\u00f3n y planificaci\u00f3n. Un servidor de Hana no es un port\u00e1til privado o una consola de juegos en la que desenchufarlo r\u00e1pidamente y luego arrancarlo resuelve la mayor\u00eda de los problemas.<\/p>\n<p>Los servidores Hana est\u00e1n integrados en una compleja red inform\u00e1tica con componentes redundantes y a prueba de fallos. La mayor\u00eda de los centros de datos de SAP funcionan 24x7.<\/p>\n<p>Incluso las actualizaciones y tareas de servicio m\u00e1s sencillas requieren una programaci\u00f3n detallada. Incorporar parches y actualizaciones de bios a nivel de hardware y sistema operativo de forma paralela es arriesgado, cuando no negligente.<\/p>\n<p>Se puede hablar de suerte si el servidor puede arrancar de nuevo en absoluto despu\u00e9s de tal \"operaci\u00f3n\". Los parches Meltdown y Spectre de Intel y Dell han creado exactamente este escenario de horror: Los dispositivos parcheados arrancaban varias veces o fallaban por completo.<\/p>\n<p>Incluso tras una evaluaci\u00f3n exhaustiva y satisfactoria en los servidores de desarrollo y prueba, sigue existiendo un riesgo residual, por lo que el consejo de SAP \"<em>Instale los parches necesarios y reinicie su host<\/em>\"s\u00f3lo debe entenderse como una broma.<\/p>\n<p>Por lo tanto, no es de extra\u00f1ar que el informe E-3 en el <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/ausgabe-1802\/\" target=\"_blank\" rel=\"noopener noreferrer\">Febrero<\/a> de la p\u00e1gina 38 provoc\u00f3 numerosas reacciones y muchas llamadas a la redacci\u00f3n. Como \"servicio\" a este angustioso tema, hay en <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/ausgabe-maerz-2018\/\" target=\"_blank\" rel=\"noopener noreferrer\">este tema<\/a> en la p\u00e1gina 68 una continuaci\u00f3n.<\/p>\n<p>Pero la irrespetuosa nota de SAP no ha sido la \u00fanica sorpresa para empezar el nuevo a\u00f1o. \u00a1SAP quiere comprar Callidus! Seg\u00fan Luka Mucic, CFO de SAP, llevan tiempo trabajando internamente con este software CRM para ventas.<\/p>\n<p>Como est\u00e1n convencidos de la funcionalidad y ya existen interfaces con el ERP de SAP, el paso era l\u00f3gico seg\u00fan Mucic: SAP quiere hacerse con la empresa estadounidense por unos 2.400 millones de d\u00f3lares.<\/p>\n<p>T\u00e9cnicamente, el software Callidus se encuadra en el \u00e1mbito de la gesti\u00f3n del rendimiento de ventas (SPM) y la configuraci\u00f3n de cotizaciones (CPQ). En la pr\u00e1ctica, es la batalla defensiva de SAP contra el software CRM de Salesforce.<\/p>\n<p>Incluso la brutal e injustificada acci\u00f3n del SAP contra los brit\u00e1nicos <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/2017\/06\/01\/sap-uk-against-diageo-legal-consequences-of-licence-violations-avoid\/\" target=\"_blank\" rel=\"noopener noreferrer\">Fabricante de bebidas Diageo<\/a> no pudo evitar que muchos clientes existentes de SAP eligieran el \"mejor\" CRM. Diageo fue condenada a pagar un elevado retroactivo de licencia -uso indirecto- porque un sistema Salesforce est\u00e1 conectado al ERP SAP.<\/p>\n<p>SAP tuvo mucha suerte en este caso: el mismo caso en Alemania no habr\u00eda tenido tanto \u00e9xito para SAP, como puede leerse claramente en este n\u00famero E-3 en la p\u00e1gina 11.<\/p>\n<p>Pero Salesforce tambi\u00e9n parece estar s\u00f3lo vagamente informada sobre las regulaciones reales de licencias de SAP. En lugar de triunfar y respaldar a sus propios clientes existentes, Salesforce en Alemania guarda un llamativo silencio. Quien piense mal de esto es un sinverg\u00fcenza.<\/p>\n<p>Con el desconocido SAP Leonardo, el l\u00edder mundial del mercado de ERP est\u00e1 probando suerte con IoT, blockchain (v\u00e9ase el art\u00edculo de portada de este n\u00famero) y tambi\u00e9n con el aprendizaje autom\u00e1tico. Este \u00faltimo se convertir\u00e1 probablemente en el hazmerre\u00edr de Walldorf, aunque el carnaval ya haya terminado.<\/p>\n<p>El aprendizaje autom\u00e1tico y tambi\u00e9n el aprendizaje profundo es la capacidad de las redes neuronales, que se replican en hardware y software, para \"aprender\" de los datos con el fin de reaccionar \"sensatamente\" despu\u00e9s: todo el sistema sigue el modelo del aprendizaje humano.<\/p>\n<p>En campos especiales como el reconocimiento de im\u00e1genes y voz, el ajedrez y el Go, la tecnolog\u00eda del aprendizaje autom\u00e1tico\/profundo funciona ahora de forma excelente. Un ordenador de Google ha aprendido por s\u00ed mismo el juego de mesa Go sin ning\u00fan conocimiento previo y ahora juega mejor que cualquier ser humano: el ser humano puede haber construido este ordenador, \u00a1pero no tiene ni idea del algoritmo Go \"autodidacta\"!<\/p>\n<p>Este es un peligro contra el que advierten muchos expertos: la red neuronal domina procesos que no pueden verificarse algor\u00edtmicamente. Por su propia naturaleza, la prueba de una sem\u00e1ntica correcta no es f\u00e1cil de encontrar ni siquiera en algoritmos escritos por humanos.<\/p>\n<p>Sin embargo, seg\u00fan un informe del Handelsblatt, el director financiero de SAP, Luka Mucic, quiere hacer transparentes precisamente estos algoritmos de IA desconocidos. Un equipo de SAP est\u00e1 trabajando en un c\u00f3digo de conducta sobre IA.<\/p>\n<p>Seg\u00fan el Handelsblatt: Entre otras cosas, la normativa estipula que los clientes deben tener conocimiento de los algoritmos. \"Si el cliente nos percibiera como una caja negra, nuestra relaci\u00f3n se resentir\u00eda\", afirma Mucic.<\/p>","protected":false},"excerpt":{"rendered":"<p>Esta frase no es una broma de carnaval sobrante, sino una recomendaci\u00f3n de la nota 2586312 de SAP relativa a Meltdown, Spectre y Hana. Qui\u00e9n conoce un servidor Hana operativo que se pueda parchear y reiniciar sobre la marcha?<\/p>","protected":false},"author":2,"featured_media":4146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[8,7,20719],"tags":[21121,304,396,21127,48,3491,10922,21140],"coauthors":[27825],"class_list":["post-34436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial","category-meinung","category-mag-1803","tag-callidus","tag-dell","tag-intel","tag-meltdown","tag-salesforce","tag-sap-hana","tag-sap-leonardo","tag-spectre"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-400x160.jpg",400,160,true],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-768x307.jpg",768,307,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-100x40.jpg",100,40,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-480x192.jpg",480,192,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-640x256.jpg",640,256,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-720x288.jpg",720,288,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-960x384.jpg",960,384,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-18x7.jpg",18,7,true],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479.jpg",1000,400,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-600x240.jpg",600,240,true],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-600x400.jpg",600,400,true],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2016\/12\/Editorial-e1699258340479-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Dieser Satz ist kein \u00fcbrig gebliebener Karnevalsscherz, sondern eine Empfehlung aus der SAP-Note 2586312 bez\u00fcglich Meltdown, Spectre und Hana. Wer kennt einen operativen Hana-Server, der sich nebenbei auf die Schnelle patchen und rebooten l\u00e4sst?<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/opinion\/editorial\/\" rel=\"category tag\">Editorial<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/opinion\/\" rel=\"category tag\">Die Meinung der SAP-Community<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-1803\/\" rel=\"category tag\">MAG 18-03<\/a>","author_info_v2":{"name":"Peter M. F\u00e4rbinger, E3-Magazin","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/peter-m-faerbinger-e-3-magazin\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/34436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=34436"}],"version-history":[{"count":0,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/34436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/4146"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=34436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=34436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=34436"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=34436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}