{"id":56905,"date":"2019-04-05T08:00:42","date_gmt":"2019-04-05T06:00:42","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=56905"},"modified":"2020-02-09T01:28:33","modified_gmt":"2020-02-09T00:28:33","slug":"gestion-ajustada-y-automatizacion","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/gestion-ajustada-y-automatizacion\/","title":{"rendered":"Gesti\u00f3n ajustada y automatizaci\u00f3n"},"content":{"rendered":"<p>Como se muestra en el n\u00famero de E-3 de febrero de 2019 en la p\u00e1gina 66, la idea DevOps tiene numerosos precursores y modelos a seguir, que influyeron principalmente en la C (Cultura), la M (Medici\u00f3n) y la S (Compartir) del concepto Calms. Pero al menos igual de importantes son los aspectos de Lean Management (L) y, sobre todo, la Automatizaci\u00f3n (A).<\/p>\n<p>Aunque en la d\u00e9cada de 1990 empezaron a surgir nuevos enfoques para desarrollar software de forma m\u00e1s r\u00e1pida y flexible, hubo que esperar hasta 2009 para reunir todos los elementos de Calms en un \u00fanico concepto.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2605032768\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-2272809019\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-512054207\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n<p>El objetivo de este enfoque es conseguir que la colaboraci\u00f3n entre desarrollo y operaciones de TI sea tan \u00e1gil y flexible como el propio desarrollo: Desde los primeros DevOps Days en Gante, las experiencias de desarrollo y de otras divisiones de la empresa se han agrupado en el concepto DevOps, como las recogidas en el manual DevOps.<\/p>\n<h3>Cambio de cultura a todos los niveles<\/h3>\n<p>La implantaci\u00f3n de DevOps exige mucho de los implicados. Todos tienen que cambiar sus actitudes, expectativas y formas de trabajar. As\u00ed, en tiempos de DevOps, la era de los prestigiosos proyectos a gran escala ha terminado.<\/p>\n<p>En su lugar, pasa a primer plano la gesti\u00f3n empresarial de un proyecto de desarrollo. Se da la vuelta a la cuesti\u00f3n b\u00e1sica: en lugar de preguntarse cu\u00e1nto costar\u00e1 el proyecto, hay que definir qu\u00e9 funcionalidades de software nuevas o mejoradas pueden realizarse con un presupuesto determinado y manejable.<\/p>\n<p>Si la respuesta est\u00e1 disponible, la direcci\u00f3n debe estar satisfecha con ella y confiar en que los participantes en el proyecto creen que se trata de objetivos realistas. Al mismo tiempo, hay que evitar el control detallado desde arriba.<\/p>\n<p><em>\"Lo que cuenta desde el punto de vista de la gesti\u00f3n es \u00fanicamente el resultado comparado con el plan, no el control de los pasos individuales. Esto es lo que se entiende por Lean en el concepto DevOps. <\/em><em>Tanto los altos directivos como los jefes de departamentos especializados, que dependen especialmente de sus colegas de inform\u00e1tica, deben someterse a este cambio de perspectiva\".<\/em><\/p>\n<p>recomienda James Roberts, Director T\u00e9cnico de Basis Technologies.<\/p>\n<p>Esto tambi\u00e9n supone un gran cambio para los gestores de lanzamientos. Ya no obtienen su reputaci\u00f3n de presentar y gestionar grandes obras, sino de completar con \u00e9xito muchos proyectos peque\u00f1os, cada uno de ellos s\u00f3lo para grupos de usuarios seleccionados en los departamentos especializados.<\/p>\n<p>Dado que los proyectos individuales son gestionables, su comprensi\u00f3n de su papel debe cambiar de l\u00edder a entrenador, motivador y formador. Tambi\u00e9n tienen que garantizar que la composici\u00f3n del equipo se mantenga estable a largo plazo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56908\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper.jpg\" alt=\"Achim Toeper\" width=\"800\" height=\"800\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-150x150.jpg 150w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-768x768.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-100x100.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-480x480.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-640x640.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-720x720.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-24x24.jpg 24w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-48x48.jpg 48w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-96x96.jpg 96w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Achim-Toeper-300x300.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>El esp\u00edritu de equipo surge no s\u00f3lo de la alineaci\u00f3n en torno a un objetivo com\u00fan, sino tambi\u00e9n de las relaciones fiables y de confianza entre los miembros del equipo. Dado que los grandes proyectos estrat\u00e9gicos en el mundo DevOps se dividen en muchos proyectos peque\u00f1os, iterativos y detallados, esto es estructuralmente posible.<\/p>\n<p>Los miembros del equipo, a su vez, deben estar dispuestos a alejarse un poco de su especialidad y compartir sus conocimientos con todos los miembros del equipo. S\u00f3lo as\u00ed podr\u00e1n comprender mejor los retos de los dem\u00e1s.<\/p>\n<p>S\u00f3lo a trav\u00e9s del intercambio en el equipo aprenden los desarrolladores qu\u00e9 problemas plantean sus artefactos a los administradores de servidores, almacenamiento y otros, tanto a la hora de proporcionar el entorno de pruebas adecuado como de transferir los cambios al entorno de producci\u00f3n.<\/p>\n<p>Este \"compartir\" (S) institucionalizado m\u00e1s all\u00e1 del pensamiento y las fronteras de los silos es el aspecto que crea confianza a trav\u00e9s del entendimiento y sienta las bases de la normalizaci\u00f3n: Normalizaci\u00f3n del enfoque, pero tambi\u00e9n de las herramientas con las que se trabaja.<\/p>\n<p>Al comprender exactamente c\u00f3mo funciona un entorno de pruebas y por qu\u00e9 sus colegas de la empresa han elegido \u00e9ste y no otro, los desarrolladores pueden evitar desde el principio muchas reparaciones y riesgos en el posterior funcionamiento productivo.<\/p>\n<p>Esto se corresponde exactamente con una de las ideas centrales del m\u00e9todo de desarrollo \u00e1gil Scrum, seg\u00fan el cual los equipos interdisciplinares son capaces de producir mejor y m\u00e1s r\u00e1pido productos nuevos y de alta calidad.<\/p>\n<p>Esta doble estandarizaci\u00f3n es el requisito previo para el componente DevOps esencial de la automatizaci\u00f3n (A). Solo un entorno estandarizado para la supervisi\u00f3n, las pruebas y la garant\u00eda de calidad puede ofrecerse como un autoservicio con el que los desarrolladores puedan trabajar de forma independiente.<\/p>\n<p>Si quieren probar un cambio de c\u00f3digo para ver si realmente ofrece la nueva funci\u00f3n deseada y qu\u00e9 impacto tiene en el sistema global, ya no tienen que esperar al equipo de operaciones, sino que pueden ponerse a trabajar directamente.<\/p>\n<p>Las operaciones inform\u00e1ticas, por su parte, pueden concentrarse plenamente en la garant\u00eda de calidad de los cambios ensamblados en una versi\u00f3n y su aplicaci\u00f3n en producci\u00f3n.<\/p>\n<p>Para mejorar continuamente la interacci\u00f3n entre el desarrollo y el funcionamiento, la medici\u00f3n (M) de los par\u00e1metros tambi\u00e9n debe automatizarse.<\/p>\n<p>Por ejemplo, evaluaciones de la rapidez y la puntualidad o informaci\u00f3n sobre la calidad, como el n\u00famero de errores detectados y su evoluci\u00f3n en el tiempo.<\/p>\n<h3>Acelerado a SAFe SAP<\/h3>\n<p>Es el cambio cultural el que provoca el cambio estructural, y no al rev\u00e9s. Al mismo tiempo, el cambio no tiene por qu\u00e9 venir de arriba al principio; al contrario, suelen ser las iniciativas de los desarrolladores afectados y de sus colegas en la empresa las que provocan la revoluci\u00f3n DevOps a la manera de los movimientos de base.<\/p>\n<p>As\u00ed lo demuestran una y otra vez los estudios, como el Informe sobre el estado de DevOps de 2018. Estos pioneros tienen tanto m\u00e1s \u00e9xito cuanto m\u00e1s manejable es la tarea que emprenden y cuanto m\u00e1s urgente es desde la perspectiva de la empresa o de un departamento especializado clave.<\/p>\n<p>En esta fase, los clientes actuales de SAP pueden recurrir al concepto Accelerated SAP, que ya describe el trabajo \u00e1gil \u00e0 la Scrum. Una vez que hayan demostrado la nueva cultura y su superioridad, pueden y deben implicar a la direcci\u00f3n a varios niveles y convertirlos en patrocinadores de la revoluci\u00f3n DevOps.<\/p>\n<p>Este apoyo desde arriba es crucial para el \u00e9xito. Porque los equipos de DevOps no pueden vivir en dos mundos al mismo tiempo, no pueden trabajar seg\u00fan el modelo de cascada por un lado y los m\u00e9todos \u00e1giles por otro, las p\u00e9rdidas por fricci\u00f3n ser\u00edan demasiado grandes.<\/p>\n<p>Esto significa, en particular, que la direcci\u00f3n libera a los miembros de los equipos DevOps de sus tareas anteriores. Deben poder concentrarse por completo en los nuevos procesos y, posiblemente, en las nuevas herramientas.<\/p>\n<p>De este modo, cada vez m\u00e1s \u00e1reas de TI pueden convertirse a DevOps pieza a pieza. Los gestores pueden encontrar una descripci\u00f3n de su nuevo papel en el marco Scaled Agile for Enterprises o SAFe de Scaled Agile, que gu\u00eda no solo a los equipos individuales, sino tambi\u00e9n a todos los niveles de gesti\u00f3n por encima de ellos en la direcci\u00f3n de DevOps.<\/p>\n<p>La confianza es clave, especialmente en el entorno SAP, donde la desconfianza hacia DevOps es quiz\u00e1 mayor debido a la complejidad y las dependencias internas y externas de los distintos componentes de los entornos SAP.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-56907\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6.jpg\" alt=\"Presentaci\u00f3n DevOps DE 2018 IDC Zacher 6\" width=\"1000\" height=\"589\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6.jpg 1000w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6-768x452.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6-100x59.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6-480x283.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6-640x377.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6-720x424.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/Praesentation_DevOps-DE_2018_IDC_Zacher-6-960x565.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Los desarrolladores y administradores de SAP dependen, m\u00e1s que casi ning\u00fan otro grupo de las TI corporativas, no s\u00f3lo de las relaciones personales, sino tambi\u00e9n de las herramientas que pueden ayudar a generar esta confianza.<\/p>\n<p>Necesitan herramientas que puedan mapear de forma fiable todas las dependencias y poner a prueba las nuevas versiones, incluidos sus efectos en los entornos productivos.<\/p>\n<p>Estas herramientas incluyen, en particular, herramientas para pruebas de regresi\u00f3n automatizadas. Las herramientas adecuadas cubren pr\u00e1cticamente todo el entorno productivo y, por tanto, ofrecen resultados tan pr\u00f3ximos a la realidad que el c\u00f3digo probado positivamente puede implantarse con un riesgo muy reducido.<\/p>\n<p>Este es el requisito previo para la entrega de versiones en entornos SAP productivos a intervalos cortos. En la jerga de DevOps, esta cadena de entrega se denomina Continuous Delivery Pipeline o, en el marco SAFe, Agile Release Train con los pasos individuales de exploraci\u00f3n, integraci\u00f3n y despliegue.<\/p>\n<p>Sin embargo, en caso de que surjan problemas como p\u00e9rdidas de rendimiento o errores funcionales notables, estas herramientas de automatizaci\u00f3n tambi\u00e9n deben ofrecer la opci\u00f3n de hacer retroceder la versi\u00f3n sin interrupci\u00f3n, tal y como los usuarios est\u00e1n acostumbrados a hacer desde la nube.<\/p>\n<h3>Automatizaci\u00f3n<\/h3>\n<p>Si hay una falta de confianza en la automatizaci\u00f3n de la parte de operaciones, las operaciones son y siguen siendo el cuello de botella que impide la introducci\u00f3n de DevOps en el entorno SAP de una empresa.<\/p>\n<p>\u00bfNo es de extra\u00f1ar que muchos clientes actuales de SAP ya est\u00e9n utilizando DevOps en sus TI, pero no en su propio entorno SAP, sino en soluciones de terceros?<\/p>\n<p>Definitivamente, las herramientas de automatizaci\u00f3n desempe\u00f1an un papel m\u00e1s importante en los entornos SAP que en otras \u00e1reas. Es m\u00e1s, aunque la cultura se encuentre en los inicios de DevOps, la automatizaci\u00f3n es igual de importante en los entornos SAP.<\/p>\n<p><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/socios\/tecnologias_de_base\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56465 size-full\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner.jpg\" alt=\"https:\/\/e3magpmp.greatsolution.dev\/partners\/basis_technologies\/\" width=\"1000\" height=\"112\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner.jpg 1000w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner-768x86.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner-100x11.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner-480x54.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner-640x72.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner-720x81.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/01\/Basis-CI-Banner-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Los clientes SAP existentes tienen m\u00e1s dificultades que otros con la introducci\u00f3n del concepto DevOps. Un cambio de cultura y las herramientas de DevOps adecuadas pueden ayudar - Parte 2: C\u00f3mo los clientes heredados de SAP est\u00e1n convirtiendo Dev and Ops en DevOps a trav\u00e9s de la automatizaci\u00f3n.<\/p>","protected":false},"author":1674,"featured_media":56906,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[5,28431],"tags":[145,451],"coauthors":[28005],"class_list":["post-56905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infrastruktur","category-mag-1903","tag-automatisierung","tag-devops"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",400,180,false],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-768x346.jpg",768,346,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-100x45.jpg",100,45,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-480x216.jpg",480,216,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-640x288.jpg",640,288,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-720x324.jpg",720,324,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",1000,450,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk.jpg",600,270,false],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/02\/shutterstock_269887781_cmyk-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>SAP-Bestandskunden ringen mehr als andere mit der Einf\u00fchrung des DevOps-Konzepts. Eine Kultur\u00e4nderung und die passenden DevOps-Tools schaffen Abhilfe \u2013 Teil 2: Wie bei SAP-Bestandskunden Dev und Ops mittels Automatisierung zu DevOps werden.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/infraestructura\/\" rel=\"category tag\">IT Management<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-1903\/\" rel=\"category tag\">MAG 19-03<\/a>","author_info_v2":{"name":"Achim T\u00f6per, Basis Technologies","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/achim-toeper\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/56905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/1674"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=56905"}],"version-history":[{"count":0,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/56905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/56906"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=56905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=56905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=56905"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=56905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}