{"id":61766,"date":"2015-09-02T12:43:31","date_gmt":"2015-09-02T10:43:31","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=61766"},"modified":"2024-01-19T14:54:33","modified_gmt":"2024-01-19T13:54:33","slug":"negocios-transfronterizos-con-clientes","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/negocios-transfronterizos-con-clientes\/","title":{"rendered":"Cruce de fronteras en el negocio de las cuentas por cobrar"},"content":{"rendered":"<p>Andreas Prantner ha sido responsable de la gesti\u00f3n de datos maestros, cr\u00e9ditos y cuentas por cobrar en RWA Raiffeisen Ware Austria como Jefe de Cuentas por Cobrar\/Creditores desde 2013.<\/p>\n<p>Una de sus primeras tareas fue finalizar el proyecto en curso y asignar la gesti\u00f3n integrada de cr\u00e9ditos y riesgos en el sistema SAP con la ayuda de complementos del socio de canal de SAP Cormeta.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-3402341484\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-308216515\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2054269288\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n<p>Los segmentos de negocio del Grupo RWA incluyen agricultura, tecnolog\u00eda, energ\u00eda, materiales de construcci\u00f3n y construcci\u00f3n y jardiner\u00eda. Como empresa matriz del Grupo, RWA se especializa principalmente en la venta al por mayor tradicional, B2B. En el sector agr\u00edcola, esto significa relaciones con molinos de grano, almazaras y fabricantes de fertilizantes.<\/p>\n<p>El Grupo tambi\u00e9n incluye dos empresas energ\u00e9ticas, Genol como mayorista y W\u00e4rme Austria como proveedor de clientes finales. Un tercio de los clientes finales son empresas comerciales y dos tercios, hogares que compran, por ejemplo, petr\u00f3leo o pellets.<\/p>\n<p><em>\"Se trata de nuestro negocio de d\u00e9bito masivo, con unos 70.000 clientes de energ\u00eda\"<\/em><\/p>\n<p>dice Prantner.<\/p>\n<p>La divisi\u00f3n de tecnolog\u00eda incluye, por un lado, el comercio de maquinaria agr\u00edcola y, por otro, la venta de neum\u00e1ticos y piezas de recambio. Aqu\u00ed, RWA tiene una estructura de clientes mixta que va desde agricultores a clientes comerciales y tambi\u00e9n exporta neum\u00e1ticos y tecnolog\u00eda al extranjero, sobre todo al sur y al este de Europa. En conjunto, se trata de una estructura de clientes muy heterog\u00e9nea que requiere una gesti\u00f3n sensible del cr\u00e9dito y del riesgo.<\/p>\n<h3>La situaci\u00f3n inicial<\/h3>\n<p>En los \u00faltimos a\u00f1os, el grupo se ha ampliado para incluir varias empresas, que primero tuvieron que centralizarse y luego integrarse en SAP.<\/p>\n<p>Como parte de las adquisiciones de empresas, RWA tambi\u00e9n se hizo cargo de contratos existentes, incluidos contratos de seguros.<\/p>\n<p><em>\"Tambi\u00e9n tenemos muchos de los mismos clientes en distintas unidades de negocio y quer\u00edamos poder asignar este riesgo de cl\u00faster de forma transparente. Gestionar esto como antes era una tarea de S\u00edsifo. El equipo existente apenas pod\u00eda con todo\".<\/em><\/p>\n<p>dice el jefe de departamento Prantner.<\/p>\n<h3>Fase I<\/h3>\n<p>Los objetivos estaban claramente definidos: en el futuro, todo deb\u00eda procesarse de forma coherente en SAP: La gesti\u00f3n de cr\u00e9ditos, el seguro de cr\u00e9dito, incluido el cumplimiento \u00edntegro de las obligaciones contractuales, la gesti\u00f3n de garant\u00edas y las comprobaciones de cr\u00e9dito directamente en SAP mediante la conexi\u00f3n con agencias de cr\u00e9dito.<\/p>\n<p>Y todo ello integrando los programas complementarios de Cormeta. La fase I del proyecto comenz\u00f3 en 2013 con el objetivo de introducir los add-ons de SAP KVsprint, RMsprint y CGsprint, es decir, las soluciones para la gesti\u00f3n de seguros de cr\u00e9dito, la gesti\u00f3n de cr\u00e9ditos y riesgos y la conexi\u00f3n con las agencias de cr\u00e9dito.<\/p>\n<h3>Fase II<\/h3>\n<p>Prantner se hizo cargo del proyecto, que ahora se encuentra en la fase II, como participante lateral en octubre de 2013. Incluye la integraci\u00f3n de los deudores en masa, la ampliaci\u00f3n de las interfaces de informaci\u00f3n y la integraci\u00f3n de las filiales de la CEE.<\/p>\n<p><em>\"Ocho personas, incluido yo mismo, trabajamos con los complementos de Cormeta. Tres est\u00e1n especializados en la gesti\u00f3n de cr\u00e9ditos y necesitan el programa a diario. Cuatro empleados se encargan de la gesti\u00f3n de las cuentas por cobrar y utilizan los complementos para llevar el control\"<\/em><\/p>\n<p>informa Prantner.<\/p>\n<p>La cabina de arranque de Cormeta ofrece una oportunidad ideal para iniciar la investigaci\u00f3n de clientes.<\/p>\n<p>En la actualidad, RWA utiliza los complementos de Cormeta KVsprint para la gesti\u00f3n del seguro de cr\u00e9dito, RMsprint para la gesti\u00f3n de riesgos y la conexi\u00f3n con agencias de cr\u00e9dito CGsprint.<\/p>\n<p>La administraci\u00f3n de los contratos de seguro en KVsprint se ha simplificado considerablemente, todos los l\u00edmites se han normalizado en RMsprint y el riesgo de agrupaci\u00f3n se ha reducido notablemente.<\/p>\n<p><em>\"Gracias a la perfecta integraci\u00f3n de los procesos, las tres soluciones funcionan como una sola. Con uno o dos clics, puedo obtener una visi\u00f3n general de un cliente, todo su historial, con l\u00edmites de cr\u00e9dito, \u00edndices de agencias de cr\u00e9dito, etc.\".<\/em><\/p>\n<p>el jefe de departamento alaba sus nuevas herramientas.<\/p>\n<p>Esto proporciona a RWA grandes ventajas, especialmente cuando trabaja con seguros de cr\u00e9dito. Todas las consultas se responden autom\u00e1ticamente de forma digital.<\/p>\n<p><em>\"Ya no hay faxes ni bandejas de entrada desbordadas. Toda la parte de facturaci\u00f3n y administraci\u00f3n para la aseguradora ha mejorado\".<\/em><\/p>\n<p>Y el nuevo sistema ya est\u00e1 cerca de amortizar la inversi\u00f3n. El proceso a\u00fan no ha concluido, pero <em>\"Hoy puedo hacer m\u00e1s con el mismo n\u00famero de empleados. Eso se nota inmediatamente\".<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Como nuevo empleado, tener que poner fin a un proyecto inform\u00e1tico en curso parece una tarea desalentadora. A menos que el socio de software, los compa\u00f1eros y el anterior jefe de proyecto hayan realizado un buen trabajo preparatorio que facilite la vinculaci\u00f3n. <\/p>","protected":false},"author":38,"featured_media":61274,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[161,2,1571],"tags":[1065,369,143],"coauthors":[19920],"class_list":["post-61766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-szene","category-sap-nachrichten","category-1571","tag-cormeta","tag-it","tag-management"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",400,155,false],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-768x297.jpg",768,297,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-100x39.jpg",100,39,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-480x186.jpg",480,186,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-640x248.jpg",640,248,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-720x279.jpg",720,279,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-960x372.jpg",960,372,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",18,7,false],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",1000,387,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",600,232,false],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015.jpg",600,232,false],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2019\/07\/2015-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>Als neuer Mitarbeiter ein sich im Gang befindliches IT-Projekt zu Ende bringen zu m\u00fcssen klingt nach einer gewaltigen Aufgabe. Es sei denn, der Softwarepartner, die Kollegen und der vorige Projektleiter haben eine gute Vorarbeit geleistet, die das Ankn\u00fcpfen erleichtert. <\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/escena\/\" rel=\"category tag\">Szene<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/sapanoptikum-2\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/1509\/\" rel=\"category tag\">MAG 15-09<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/e-3-magazin\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/61766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=61766"}],"version-history":[{"count":1,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/61766\/revisions"}],"predecessor-version":[{"id":138491,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/61766\/revisions\/138491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/61274"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=61766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=61766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=61766"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=61766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}