{"id":65670,"date":"2020-04-20T08:00:54","date_gmt":"2020-04-20T06:00:54","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=65670"},"modified":"2024-01-19T14:48:55","modified_gmt":"2024-01-19T13:48:55","slug":"como-cumpliran-la-legislacion-los-minoristas-a-partir-de-2020","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/como-cumpliran-la-legislacion-los-minoristas-a-partir-de-2020\/","title":{"rendered":"\u00bfC\u00f3mo seguir\u00e1n cumpliendo la ley los minoristas a partir de 2020?"},"content":{"rendered":"<p>E-3 Magazine habl\u00f3 con Stephan Kaup, Director General de Consult-SK, que se enfrenta regularmente a preguntas sobre fiscalizaci\u00f3n en su contacto diario con usuarios de SAP del sector minorista.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\" data-block-type=\"core\">Se\u00f1or Kaup, \u00bfa qu\u00e9 innovaciones se enfrentan los minoristas en relaci\u00f3n con el tratamiento de los datos de los puntos de venta?<\/h4>\r\n\r\n\r\n\r\n<p><strong>Stephan Kaup: <\/strong>La Ley de caja registradora estipula que todas las reservas y los registros necesarios deben realizarse de forma individual, completa, correcta, puntual y organizada.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2956607473\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-82319245\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-3549600357\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\r\n\r\n\r\n\r\n<p>Los ingresos y gastos en efectivo deben registrarse diariamente. Una novedad importante es la obligaci\u00f3n de expedir recibos. A partir de 2020, los sistemas de registro electr\u00f3nico tambi\u00e9n deber\u00e1n contar con un dispositivo t\u00e9cnico de seguridad (TSE) certificado por la BSI (Oficina Federal de Seguridad de la Informaci\u00f3n).<\/p>\r\n\r\n\r\n\r\n<p>Varios fabricantes de sistemas de punto de venta est\u00e1n actualmente en proceso de certificaci\u00f3n. Adem\u00e1s, dos proveedores (Swissbit y Epson) ya cuentan con una EET certificada por BSI.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\" data-block-type=\"core\">\u00bfQu\u00e9 valor a\u00f1adido aporta todo el cambio?<\/h4>\r\n\r\n\r\n\r\n<p><strong>Kaup: <\/strong>Esencialmente, las autoridades financieras est\u00e1n preocupadas por proteger los datos de las cajas registradoras de manipulaciones y simplificar enormemente la auditor\u00eda de una contabilidad correcta.<\/p>\r\n\r\n\r\n\r\n<p>Hay que crear una interfaz digital que, gracias a una norma uniforme, permita recuperar registros de datos completos en cualquier momento.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" title=\"\u00bfC\u00f3mo cumplir\u00e1n los minoristas la legislaci\u00f3n a partir de 2020?\" class=\"wp-image-65673\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup.jpg\" alt=\"\u00bfC\u00f3mo cumplir\u00e1n los minoristas la legislaci\u00f3n a partir de 2020?\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-150x150.jpg 150w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-768x768.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-100x100.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-480x480.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-640x640.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-720x720.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-24x24.jpg 24w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-48x48.jpg 48w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-96x96.jpg 96w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/Stephan-Kaup-300x300.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\" data-block-type=\"core\">\u00bfQu\u00e9 significa \"DSFinV-K\" en este contexto?<\/h4>\r\n\r\n\r\n\r\n<p><strong>Kaup: <\/strong>La interfaz digital de Hacienda para los sistemas de caja registradora exige que todas las empresas que utilicen un sistema de caja registradora informatizado utilicen la misma estructura para la introducci\u00f3n y exportaci\u00f3n de datos. Se trata, por tanto, de una cuesti\u00f3n de forma de preparaci\u00f3n de los datos.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\" data-block-type=\"core\">\u00bfY qu\u00e9 cree que deber\u00edan hacer los minoristas?<\/h4>\r\n\r\n\r\n\r\n<p><strong>Kaup:<\/strong> Mi consejo es que consulte con el fabricante de su caja registradora para planificar una ampliaci\u00f3n de la salida de recibos y la integraci\u00f3n de una EET si es necesario. Una pregunta importante que los minoristas deber\u00edan plantearse en este contexto: \u00bfC\u00f3mo est\u00e1 prevista la exportaci\u00f3n a DSFinV-K? Adem\u00e1s del temor a posibles sanciones, los clientes de SAP se enfrentan a la cuesti\u00f3n de c\u00f3mo pueden vincularse y gestionarse de forma significativa los datos de su sistema de TPV convertido con su contabilidad financiera en el sistema SAP.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\" data-block-type=\"core\">Al final, \u00bfs\u00f3lo la Agencia Tributaria se beneficiar\u00e1 de una opci\u00f3n de auditor\u00eda r\u00e1pida?<\/h4>\r\n\r\n\r\n\r\n<p><strong>Kaup: <\/strong>En mi opini\u00f3n, la tem\u00e1tica centrada en la caja registradora y los requisitos actuales son demasiado limitados. Al analizar actualmente los requisitos nuevos y antiguos y los procesos asociados, se comprueba a menudo que un gran n\u00famero de requisitos existentes no se cumplen.<\/p>\r\n\r\n\r\n\r\n<p>Y no s\u00f3lo en la propia caja registradora, sino en todo el proceso hasta la contabilidad financiera. Con nuestro complemento SAP Receipt4S, tambi\u00e9n ofrecemos una soluci\u00f3n que gestiona todos los datos relevantes para el proceso de auditor\u00eda de caja de forma hist\u00f3rica, en sistemas SAP y no SAP.<\/p>\r\n\r\n\r\n\r\n<p>Por supuesto, tambi\u00e9n se incluye el archivado, el registro de cambios y el suministro de datos con fines de auditor\u00eda. Esto significa que los clientes de SAP tambi\u00e9n podr\u00e1n llevar a cabo f\u00e1cilmente una contabilidad conforme a las auditor\u00edas en 2020.<\/p>\r\n\r\n\r\n\r\n<p>Los requisitos para utilizar nuestro complemento certificado por SAP son muy sencillos: un NetWeaver con una pila Abap. No se requieren componentes espec\u00edficos de m\u00f3dulo.<\/p>\r\n\r\n\r\n\r\n<p>ArchiveLink sirve de infraestructura. Adem\u00e1s, los clientes no tendr\u00e1n que preocuparse ni siquiera despu\u00e9s de 2024\/25: Receipt4S funciona tanto en R\/3 como en S\/4 Hana.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\" data-block-type=\"core\">Gracias por la entrevista.<\/h4>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/socios\/consultar-sk-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"112\" title=\"\u00bfC\u00f3mo cumplir\u00e1n los minoristas la legislaci\u00f3n a partir de 2020?\" class=\"wp-image-65672\" src=\"http:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner.jpg\" alt=\"https:\/\/e3magpmp.greatsolution.dev\/partners\/consult-sk-gmbh\/\" srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner.jpg 1000w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner-768x86.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner-100x11.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner-480x54.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner-640x72.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner-720x81.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2020\/03\/SK-Consult-CI-Banner-960x108.jpg 960w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>KassenSichV, TSE, DSFinV-K: son palabras de moda que actualmente suscitan dudas en el sector minorista. Con la promulgaci\u00f3n de la Ordenanza de Seguridad de las Cajas Registradoras, el legislador quiso garantizar que los registros digitales de los procesos de compra no puedan ser manipulados.<\/p>","protected":false},"author":38,"featured_media":54440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[2,37393,161],"tags":[],"coauthors":[19920],"class_list":["post-65670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sap-nachrichten","category-mag-2003","category-szene"],"featured_image_urls_v2":{"full":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"thumbnail":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-150x150.jpg",150,150,true],"medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",400,180,false],"medium_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-768x346.jpg",768,346,true],"large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"image-100":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-100x45.jpg",100,45,true],"image-480":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-480x216.jpg",480,216,true],"image-640":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-640x288.jpg",640,288,true],"image-720":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-720x324.jpg",720,324,true],"image-960":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-960x432.jpg",960,432,true],"image-1168":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"image-1440":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"image-1920":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"1536x1536":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"2048x2048":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"trp-custom-language-flag":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",18,8,false],"bricks_large_16x9":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"bricks_large":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"bricks_large_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",1000,450,false],"bricks_medium":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",600,270,false],"bricks_medium_square":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview.jpg",600,270,false],"profile_24":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-24x24.jpg",24,24,true],"profile_48":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-48x48.jpg",48,48,true],"profile_96":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-96x96.jpg",96,96,true],"profile_150":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-150x150.jpg",150,150,true],"profile_300":["https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2018\/08\/interview-300x300.jpg",300,300,true]},"post_excerpt_stackable_v2":"<p>KassenSichV, TSE, DSFinV-K \u2013 das sind Schlagworte, die im Einzelhandel derzeit Fragen aufwerfen. Mit dem Erlass der Kassensicherungsverordnung wollte der Gesetzgeber sicherstellen, dass digitale Aufzeichnungen von Kaufprozessen nicht manipuliert werden k\u00f6nnen.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/sapanoptikum-2\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-2003\/\" rel=\"category tag\">MAG 20-03<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/escena\/\" rel=\"category tag\">Szene<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/e-3-magazin\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/65670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=65670"}],"version-history":[{"count":1,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/65670\/revisions"}],"predecessor-version":[{"id":137902,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/65670\/revisions\/137902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media\/54440"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=65670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=65670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=65670"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=65670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}