{"id":92979,"date":"2021-09-17T08:00:00","date_gmt":"2021-09-17T06:00:00","guid":{"rendered":"https:\/\/e3magpmp.greatsolution.dev\/?p=92979"},"modified":"2021-09-17T10:43:35","modified_gmt":"2021-09-17T08:43:35","slug":"datos-de-prueba-proteccion-y-calidad-de-los-datos","status":"publish","type":"post","link":"https:\/\/e3magpmp.greatsolution.dev\/es\/datos-de-prueba-proteccion-y-calidad-de-los-datos\/","title":{"rendered":"Datos de prueba: Protecci\u00f3n y calidad de los datos"},"content":{"rendered":"<p>Para ello, es necesario autorizar a los desarrolladores internos o a expertos externos a acceder al sistema de desarrollo. Tambi\u00e9n se necesitan datos de prueba realistas y detallados para un desarrollo de alta calidad.<\/p>\n\n\n\n<p>El dilema se hace patente cuando la protecci\u00f3n de datos sensibles choca con la posibilidad de lograr resultados de alta calidad.<\/p><div class=\"great-fullsize-content-es\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2522293343\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/kit-de-medios\/\" target=\"_blank\" aria-label=\"nl_werbung_800x100_es\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100_es-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-en\" id=\"great-3932010608\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/en\/media-kit\/\" target=\"_blank\" aria-label=\"nl_advertising_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100.jpg 800w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2024\/08\/nl_werbung_800x100-600x75.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" width=\"1000\" height=\"100\"   \/><\/a><\/div><div class=\"great-fullsize-content-de\" style=\"margin-bottom: 20px;margin-left: auto;margin-right: auto;text-align: center;\" id=\"great-2204612529\"><a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/steampunk-summit-2025\/\" target=\"_blank\" aria-label=\"steampunk_2024_1_800x100\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-scaled.jpg 1920w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-400x50.jpg 400w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1200x150.jpg 1200w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-768x96.jpg 768w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-100x13.jpg 100w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-480x60.jpg 480w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-640x80.jpg 640w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-720x90.jpg 720w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-960x120.jpg 960w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1168x146.jpg 1168w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1440x180.jpg 1440w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-1536x192.jpg 1536w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-18x2.jpg 18w, https:\/\/e3magpmp.greatsolution.dev\/wp-content\/uploads\/2023\/12\/steampunk_2024_1_800x100-600x75.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" width=\"2560\" height=\"320\"   \/><\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" data-block-type=\"core\">Autorizaciones<\/h3>\n\n\n\n<p>La protecci\u00f3n de la informaci\u00f3n sensible puede implicar la eliminaci\u00f3n de parte de los datos. Sin embargo, esto se traduce en un deterioro de la calidad del entorno de desarrollo. Este deterioro puede llevar incluso a la incoherencia del sistema. <\/p>\n\n\n\n<p>Por otro lado, proporcionar un entorno de desarrollo de alta calidad puede dar lugar a que la informaci\u00f3n sensible sea accesible a personas que no est\u00e1n autorizadas a verla. Si hay que eliminar datos del sistema SAP ERP, los equipos responsables se enfrentan a dos grandes retos:<\/p>\n\n\n\n<p>En primer lugar, la trazabilidad de los cambios en el sistema. Si los usuarios empresariales modifican los datos afectados mediante transacciones est\u00e1ndar, el sistema registra estos cambios y conserva as\u00ed los datos originales, por ejemplo los documentos de modificaci\u00f3n de proveedores y clientes.<\/p>\n\n\n\n<p>En segundo lugar, la interconectividad de los sistemas ERP. Si los usuarios empresariales eliminan los registros de datos directamente a nivel de tabla, se producen incoherencias en el sistema SAP. Por ejemplo, los pedidos de venta podr\u00edan hacer referencia a una clave maestra de cliente que ya no existe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" data-block-type=\"core\">Archivo<\/h3>\n\n\n\n<p>Para evitar estos dos problemas, la norma SAP ofrece la posibilidad de archivar. Sin embargo, el archivado s\u00f3lo puede utilizarse para procesar datos maestros para los que ya no hay transacciones abiertas, y el mejor resultado posible es el borrado coherente de los datos, lo que significa que no puede proporcionarse un entorno de desarrollo \u00f3ptimo.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" data-block-type=\"core\">El dilema<\/h3>\n\n\n\n<p>Una forma elegante de superar el dilema y proporcionar datos detallados en el entorno de desarrollo de forma que se proteja la informaci\u00f3n sensible es enmascarar sistem\u00e1ticamente estos registros de datos. En el sistema SAP, los datos se almacenan a veces en diferentes tablas y, en casos especiales, la informaci\u00f3n importante tambi\u00e9n se almacena en cadenas. <\/p>\n\n\n\n<p>Esta caracter\u00edstica dificulta enormemente la localizaci\u00f3n de todas las tablas y campos relevantes para el enmascaramiento de datos. Una vez identificados los lugares de almacenamiento de estos datos, sigue siendo necesario garantizar que el enmascaramiento se realiza de forma coherente y en todo el sistema.<\/p>\n\n\n\n<p>Se trata de una tarea de gran envergadura que requiere conocimientos especializados detallados, que tal vez haya que adquirir primero, y que tambi\u00e9n exige recursos que podr\u00edan utilizarse mejor en otros lugares y para otros procesos.<\/p>\n\n\n\n<p>Es dif\u00edcil para el usuario especializado juzgar si realmente se han tenido en cuenta todas las ubicaciones de almacenamiento. Empresas especializadas como Epi-Use Labs ofrecen software est\u00e1ndar especialmente desarrollado para el enmascaramiento de datos. Este software debe ser lo suficientemente flexible como para poder mapear las caracter\u00edsticas especiales del sistema SAP de una empresa.<\/p>\n\n\n\n<p>Los datos sensibles se protegen de conformidad con el GDPR y, al mismo tiempo, se proporciona un entorno de desarrollo eficaz que satisface los elevados requisitos de las empresas, en constante evoluci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un aspecto importante de la adaptaci\u00f3n de una empresa a la evoluci\u00f3n del mercado y a los avances tecnol\u00f3gicos es integrar las innovaciones tecnol\u00f3gicas y los nuevos conocimientos.<\/p>","protected":false},"author":38,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[2,39637],"tags":[1993,777],"coauthors":[19920],"class_list":["post-92979","post","type-post","status-publish","format-standard","hentry","category-sap-nachrichten","category-mag-21-07","tag-datenschutz","tag-qualitaet"],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","image-100":"","image-480":"","image-640":"","image-720":"","image-960":"","image-1168":"","image-1440":"","image-1920":"","1536x1536":"","2048x2048":"","trp-custom-language-flag":"","bricks_large_16x9":"","bricks_large":"","bricks_large_square":"","bricks_medium":"","bricks_medium_square":"","profile_24":"","profile_48":"","profile_96":"","profile_150":"","profile_300":""},"post_excerpt_stackable_v2":"<p>Ein wichtiger Aspekt, um ein Unternehmen an die Entwicklungen des Marktes und den Fortschritt der Technologie anzupassen, ist, technologische Neuerungen und neues Know-how zu integrieren.<\/p>\n","category_list_v2":"<a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/sapanoptikum-2\/\" rel=\"category tag\">Community Nachrichten<\/a>, <a href=\"https:\/\/e3magpmp.greatsolution.dev\/es\/categoria\/mag-21-07\/\" rel=\"category tag\">MAG 21-07<\/a>","author_info_v2":{"name":"E-3 Magazin","url":"https:\/\/e3magpmp.greatsolution.dev\/es\/author\/e-3-magazin\/"},"comments_num_v2":"0 comentarios","acf":[],"_links":{"self":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/92979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/comments?post=92979"}],"version-history":[{"count":0,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/posts\/92979\/revisions"}],"wp:attachment":[{"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/media?parent=92979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/categories?post=92979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/tags?post=92979"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/e3magpmp.greatsolution.dev\/es\/wp-json\/wp\/v2\/coauthors?post=92979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}